{"id":7312,"date":"2020-12-30T15:34:10","date_gmt":"2020-12-30T14:34:10","guid":{"rendered":"https:\/\/www.havenhostel.de\/?post_type=bhv&#038;p=7312"},"modified":"2024-11-26T15:30:14","modified_gmt":"2024-11-26T14:30:14","slug":"datenschutz","status":"publish","type":"bhv","link":"https:\/\/www.havenhostel.de\/de\/bhv\/datenschutz\/","title":{"rendered":"Datenschutz"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"7312\" class=\"elementor elementor-7312\" data-elementor-post-type=\"bhv\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-78cbec24 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"78cbec24\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-61e5c8c6\" data-id=\"61e5c8c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11885ed4 elementor-widget elementor-widget-text-editor\" data-id=\"11885ed4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<p class=\"wp-block-paragraph\"><strong>1. Allgemein<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Die havenhostel Bremerhaven GmbH freut sich \u00fcber Ihren Besuch auf unserer Website und \u00fcber Ihr Interesse an unserem Unternehmen. Das havenhostel Bremerhaven m\u00f6chte Sie mit der Internetseite \u00fcber bestehende Produkte und Leistungen informieren. Der Schutz Ihrer privaten Daten ist uns bei der Verarbeitung personenbezogener Daten ein wichtiges Anliegen, das wir bei s\u00e4mtlichen Gesch\u00e4ftsprozessen stets ber\u00fccksichtigen. Wir weisen zudem daraufhin, dass unsere Mitarbeiter an das Datengeheimnis gem\u00e4\u00df Bundesdatenschutzgesetz verpflichtet sind.<\/p>\n\n<p class=\"wp-block-paragraph\"><br \/><strong>Personenbezogene Daten<\/strong><br \/>Bei personenbezogenen Daten handelt es sich um Daten, die Ihrer Person zugeordnet werden k\u00f6nnen (z.B. Ihr Name oder Ihr Geburtsdatum).<\/p>\n\n<p class=\"wp-block-paragraph\">Mit dieser Datenschutzerkl\u00e4rung unterrichten wir Sie dar\u00fcber, in welcher Art, in welchem Umfang und zu welchem Zweck wir personenbezogene Daten von Ihnen erheben, wenn Sie die Internetseite der havenhostel Bremerhaven GmbH besuchen.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>2. Genereller Umgang mit Ihren pers\u00f6nlichen Daten<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Die havenhostel Bremerhaven GmbH nimmt den Schutz Ihrer pers\u00f6nlichen Daten sehr ernst. Regelm\u00e4\u00dfig kann unsere Webseite ohne die Weitergabe pers\u00f6nlicher Daten genutzt werden. Wenn wir personenbezogene Daten erheben \u2013 etwa Ihren Namen, Ihre Anschrift oder Ihre E-Mail-Adresse \u2013 erfolgt diese Datenerhebung freiwillig. Ohne eine ausdr\u00fccklich erteilte Zustimmung von Ihrer Seite werden diese Daten nicht an Dritte \u00fcbermittelt. Beachten Sie bitte, dass Daten im Internet allgemein nicht immer sicher \u00fcbertragen werden. Besonders im E-Mail-Verkehr kann der Schutz beim Datenaustausch nicht garantiert werden.<\/p>\n\n<p class=\"wp-block-paragraph\">Pers\u00f6nliche Daten, die Sie uns online (per E-Mail oder anhand von Web-Formularen) freiwillig \u00fcbermitteln, werden entsprechend der gesetzlichen Vorschriften erfasst und verarbeitet. Personenbezogene Daten, die im Rahmen unserer Reservierungsanfragen, Buchungen, zur Bearbeitung von Anfragen, zur Abwicklung von Bestellungen oder bei Anfragen per E-Mail oder \u00fcber das Kontaktformular \u00fcbermittelt werden, werden ausschlie\u00dflich f\u00fcr den Zweck verwendet, f\u00fcr den sie \u00fcberlassen wurden, und werden nicht an Dritte weitergegeben. Personenbezogene Daten, die im Rahmen einer allgemeinen Kontaktanfrage per E-Mail oder Kontaktformular von uns verarbeitet werden, speichern wir nur so lange, wie dies f\u00fcr die jeweilige Korrespondenz notwendig ist (Rechtsgrundlage Einwilligung gem. Artikel 6 DSGVO).<\/p>\n\n<p class=\"wp-block-paragraph\">Diese Website der havenhostel Bremerhaven GmbH nutzt aus Gr\u00fcnden der Sicherheit und zum Schutz der \u00dcbertragung vertraulicher Inhalte eine SSL-Verschl\u00fcsselung. Eine verschl\u00fcsselte Verbindung erkennen Sie daran, dass die Adresszeile des Browsers von \u201ehttp:\/\/\u201c auf \u201ehttps:\/\/\u201c wechselt und an dem Schloss-Symbol in Ihrer Browserzeile.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>3. Serverlogfiles<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Mit Aufruf der Website der havenhostel Bremerhaven GmbH werden weder personenbezogene Daten erfasst noch Nutzungsprofile zu Ihrer Person erstellt. Auf unserem Server werden Logfiles \u00fcber den Zugriff des Nutzers der Seiten aufgezeichnet. Eine Identifizierung des Nutzers findet nicht statt. Bei jedem Zugriff eines Nutzers auf unser Internetangebot und bei jedem Abruf einer Datei werden lediglich Zugriffsdaten \u00fcber diesen Vorgang in einer Protokolldatei auf unserem Server gespeichert. Bei dieser sogenannten &#8222;informatorischen Nutzung&#8220; erheben wir ausschlie\u00dflich die Daten, die Ihr Browser \u00fcbermittelt, um Ihnen den Besuch der Website zu erm\u00f6glichen. Darunter fallen die folgenden Daten:<\/p>\n\n<p class=\"wp-block-paragraph\">\u2022 Die IP-Adresse<br \/>\u2022 Datum und Uhrzeit der Anforderung<br \/>\u2022 Die aufgerufene Seite bzw. der Name der abgerufenen Datei<br \/>\u2022 Die \u00fcbertragene Datenmenge<br \/>\u2022 Eine Meldung, ob der Zugriff bzw. Abruf erfolgreich war<br \/>\u2022 Website, von der die Anforderung kommt<br \/>\u2022 Browser<br \/>\u2022 Betriebssystem und dessen Oberfl\u00e4che<br \/>\u2022 Sprache und Version der Browsersoftware\u00a0<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>4. Widerruf und Auskunftsrecht<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Wenn Sie uns eine Einwilligung zur Nutzung personenbezogener Daten gegeben haben, k\u00f6nnen Sie diese Einwilligung jederzeit widerrufen. Ihre personenbezogenen Daten werden wir dann l\u00f6schen, sofern wir nicht zur Aufbewahrung aus gesetzlichen Vorschriften verpflichtet sind. Nur mit Ihrer ausdr\u00fccklichen Zustimmung, die jedoch jederzeit widerrufen werden kann, werden die Daten nur von uns f\u00fcr Zwecke der Werbung und Marktforschung genutzt. Ihre Daten werden entsprechend den gesetzlichen Datenschutzbestimmungen gespeichert und verarbeitet. Der Widerruf kann jederzeit per E-Mail oder per Post erfolgen:<br \/><br \/>havenhostel Bremerhaven GmbH<br \/>Dillinger Str. 3<br \/>27578 Bremerhaven<\/p>\n\n<p class=\"wp-block-paragraph\">E-Mail:\u00a0<a href=\"mailto:datenschutz@havenhostel.de\">datenschutz@havenhostel.de<\/a>\u00a0<\/p>\n\n<p class=\"wp-block-paragraph\">Sie erhalten jederzeit unentgeltlich Auskunft \u00fcber die von uns gespeicherten personenbezogenen Daten zu Ihrer Person; zur Herkunft, dem Empf\u00e4nger und dem Zweck der Datenerhebung sowie der Datenverarbeitung. Zudem haben Sie das Recht, die Berichtigung, die Sperrung oder L\u00f6schung Ihrer Daten zu verlangen. Ausgenommen davon sind Daten, die aufgrund gesetzlicher Vorschriften aufbewahrt oder zur ordnungsgem\u00e4\u00dfen Gesch\u00e4ftsabwicklung ben\u00f6tigt werden.<\/p>\n\n<p class=\"wp-block-paragraph\">Ihnen stehen folgende Rechte gem\u00e4\u00df Datenschutzgrundverordnung (DSGVO) zu:<\/p>\n\n<p class=\"wp-block-paragraph\">Recht auf Auskunft:\u00a0<br \/>Sie k\u00f6nnen gem\u00e4\u00df Artikel 15 DSGVO eine Best\u00e4tigung dar\u00fcber verlangen, ob Sie betreffende Daten verarbeitet werden. Ist dies der Fall, so haben Sie ein Recht auf Auskunft \u00fcber die verarbeiteten Informationen.<br \/><br \/>Recht auf Widerruf der Einwilligung:<br \/>Sofern die Verarbeitung Ihrer personenbezogenen Daten aufgrund einer Einwilligung erfolgt, haben Sie gem\u00e4\u00df Artikel 7 DSGVO das Recht, diese Einwilligung jederzeit zu widerrufen.<br \/><br \/>Recht auf Widerspruch:\u00a0<br \/>Sofern die Verarbeitung Ihrer personenbezogenen Daten zur Wahrung der berechtigten Interessen unseres Unternehmens erforderlich ist, k\u00f6nnen Sie gem\u00e4\u00df Artikel 21 DSGVO jederzeit Widerspruch gegen die Verarbeitung einlegen.<br \/><br \/>Recht auf L\u00f6schung:\u00a0<br \/>Sofern Sie Ihre Einwilligung widerrufen haben, Widerspruch gegen die Verarbeitung Ihrer personenbezogenen Daten eingelegt haben (und keine vorrangigen berechtigten Gr\u00fcnde f\u00fcr die Verarbeitung vorliegen), Ihre personenbezogenen Daten f\u00fcr die Zwecke der Verarbeitung nicht mehr notwendig sind, eine entsprechende rechtliche Verpflichtung besteht oder Ihre personenbezogenen Daten unrechtm\u00e4\u00dfig verarbeitet wurden, haben Sie das Recht, gem\u00e4\u00df Artikel 17 DSGVO die L\u00f6schung Ihrer personenbezogenen Daten zu verlangen.<br \/><br \/>Recht auf Berichtigung:<br \/>Sofern Ihre personenbezogenen Daten unrichtig verarbeitet wurden, haben Sie gem\u00e4\u00df Artikel 16 DSGVO das Recht, unverz\u00fcglich die Berichtigung dieser Daten zu verlangen.<\/p>\n\n<p class=\"wp-block-paragraph\">Recht auf Einschr\u00e4nkung der Verarbeitung:<br \/>Unter den Voraussetzungen des Artikels 18 DSGVO haben Sie das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/p>\n\n<p class=\"wp-block-paragraph\">Recht auf Daten\u00fcbertragbarkeit:<br \/>Ihnen steht gem\u00e4\u00df Artikel 20 DSGVO das Recht zu, von Ihnen bereitgestellte personenbezogene Daten in einem strukturierten, g\u00e4ngigen und maschinenlesbaren Format zu erhalten.<br \/><br \/>Beschwerderecht:<br \/>Ihnen steht gem\u00e4\u00df Artikel 13 DSGVO ein Beschwerderecht bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde zu.<\/p>\n\n<p class=\"wp-block-paragraph\">Die Landesdatenschutzbeauftragte des Landes Bremen ist:<br \/>Frau Dr. Imke Sommer<\/p>\n\n<p class=\"wp-block-paragraph\">Die Landesbeauftragte f\u00fcr Datenschutz und Informationsfreiheit der Freien Hansestadt Bremen<\/p>\n\n<p class=\"wp-block-paragraph\">Arndtstra\u00dfe 1<br \/>27570 Bremerhaven<\/p>\n\n<p class=\"wp-block-paragraph\">Tel.:\u00a0 \u00a0 \u00a0+ 49 471 596 2010<br \/>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0+ 49 421 361 2010<br \/>Fax:\u00a0 \u00a0 \u00a0+ 49 421 496 18495<br \/>E-Mail:\u00a0\u00a0<a href=\"mailto:office@datenschutz.bremen.de\">office@datenschutz.bremen.de\u00a0<\/a><br \/><br \/>Sollten Sie Fragen und Anregungen zur Verarbeitung Ihrer personenbezogenen Daten durch uns haben, k\u00f6nnen Sie sich an unsere betriebliche Datenschutzbeauftragte wenden:<br \/><br \/>havenhostel Bremerhaven GmbH<br \/>Datenschutzbeauftragte<br \/>Frau Alina Grotel\u00fcschen<br \/>Dillinger Str. 3<br \/>27578 Bremerhaven<\/p>\n\n<p class=\"wp-block-paragraph\">E-Mail:\u00a0<a href=\"mailto:datenschutz@havenhostel.de\">datenschutz@havenhostel.de<\/a><br \/>Fax:\u00a0 \u00a0 \u00a00471\/309 666 -99<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>5. Verwendung und L\u00f6schung von Cookies<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Die Internetseite der havenhostel Bremerhaven GmbH verwendet teilweise so genannte Cookies. Cookies dienen dazu, unser Angebot nutzerfreundlicher, effektiver und sicherer zu machen. Cookies sind kleine Textdateien, die auf Ihrem Rechner abgelegt werden und die Ihr Browser speichert. Die meisten der von uns verwendeten Cookies sind so genannte \u201eSession-Cookies\u201c. Sie werden nach Ende Ihres Besuchs automatisch gel\u00f6scht. Andere Cookies bleiben auf Ihrem Endger\u00e4t gespeichert, bis Sie diese l\u00f6schen. Diese Cookies erm\u00f6glichen es uns, Ihren Browser beim n\u00e4chsten Besuch wiederzuerkennen.<br \/><br \/>Sie k\u00f6nnen Ihren Browser so einstellen, dass Sie \u00fcber das Setzen von Cookies informiert werden und Cookies nur im Einzelfall erlauben, die Annahme von Cookies f\u00fcr bestimmte F\u00e4lle oder generell ausschlie\u00dfen sowie das automatische L\u00f6schen der Cookies beim Schlie\u00dfen des Browsers aktivieren. Bei der Deaktivierung von Cookies kann die Funktionalit\u00e4t dieser Website eingeschr\u00e4nkt sein.<br \/><br \/>Daten, die im Zusammenhang mit der Verwendung von Cookies verarbeitet werden, werden aufgrund des wirtschaftlichen Interesses unseres Unternehmens verarbeitet (Rechtsgrundlage Artikel 6 DSGVO).<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>6. Analysedienste<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Datenschutzhinweis von Google Analytics<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Diese Website benutzt Google Analytics, einen Webanalysedienst der Google Inc. (\u201eGoogle\u201c). Anbieter ist die Google Inc., 1600 Amphitheatre Parkway Mountain View, CA 94043, USA.<br \/><br \/>Google Analytics verwendet sog. \u201eCookies\u201c, Textdateien, die auf Ihrem Computer gespeichert werden und die eine Analyse der Benutzung der Website durch Sie erm\u00f6glichen. Die durch den Cookie erzeugten Informationen \u00fcber Ihre Benutzung dieser Website werden in der Regel an einen Server von Google in den USA \u00fcbertragen und dort gespeichert. Aufgrund der Aktivierung der IP-Anonymisierung auf dieser Website, wird Ihre IP-Adresse von Google jedoch innerhalb von Mitgliedsstaaten der Europ\u00e4ischen Union oder in anderen Vertragsstaaten des Abkommens \u00fcber den Europ\u00e4ischen Wirtschaftsraum zuvor gek\u00fcrzt. Nur in Ausnahmef\u00e4llen wird die volle IP-Adresse an einen Server von Google in den USA \u00fcbertragen und dort gek\u00fcrzt. Im Auftrag des Betreibers dieser Website wird Google diese Informationen benutzen, um Ihre Nutzung der Website auszuwerten, um Reports \u00fcber die Websiteaktivit\u00e4ten zusammenzustellen und um weitere mit der Websitenutzung und der Internetnutzung verbundene Dienstleistungen gegen\u00fcber dem Websitebetreiber zu erbringen. Die im Rahmen von Google Analytics von Ihrem Browser \u00fcbermittelte IP-Adresse wird nicht mit anderen Daten von Google zusammengef\u00fchrt.<br \/><br \/>Sie k\u00f6nnen die Speicherung der Cookies durch eine entsprechende Einstellung Ihrer Browser-Software verhindern; wir weisen Sie jedoch darauf hin, dass Sie in diesem Fall gegebenenfalls nicht s\u00e4mtliche Funktionen dieser Website vollumf\u00e4nglich werden nutzen k\u00f6nnen. Sie k\u00f6nnen dar\u00fcber hinaus die Erfassung der durch den Cookie erzeugten und auf Ihre Nutzung der Website bezogenen Daten (inkl. Ihrer IP-Adresse) an Google sowie die Verarbeitung dieser Daten durch Google verhindern, indem Sie das unter dem folgenden Link verf\u00fcgbare Browser-Plugin herunterladen und installieren:<br \/><br \/><a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de<\/a><br \/><br \/>Sie k\u00f6nnen die Erfassung Ihrer Daten durch Google Analytics verhindern, indem Sie auf folgenden Link klicken. Es wird ein Opt-Out-Cookie gesetzt, der die Erfassung Ihrer Daten bei zuk\u00fcnftigen Besuchen dieser Website verhindert:<br \/><br \/>Google Analytics deaktivieren:<br \/>N\u00e4here Informationen zu Nutzungsbedingungen und Datenschutz finden Sie unter<\/p>\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.google.com\/analytics\/terms\/de.html\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/www.google.com\/analytics\/terms\/de.html<\/a><br \/><a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/policies.google.com\/privacy?hl=de<\/a><br \/><br \/>Wir weisen darauf hin, dass auf dieser Website Google Analytics um den Code \u201egat._anonymizeIp();\u201c erweitert wurde, um eine anonymisierte Erfassung von IP-Adressen (sog. IP-Masking) zu gew\u00e4hrleisten.<br \/><br \/>Daten, die im Zusammenhang mit der Verwendung von Analysediensten verarbeitet werden, werden aufgrund des wirtschaftlichen Interesses unseres Unternehmens verarbeitet. (Rechtsgrundlage Artikel 6 DSGVO).<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>7. Kontaktformular<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Angaben, die Sie uns beim Ausf\u00fcllen von Kontaktformularen oder per E-Mail \u00fcbermitteln, verwenden<br \/>wir vertraulich. Ihre Daten werden ausschlie\u00dflich verarbeitet, um Ihre Anfrage zu bearbeiten und mit Ihnen hierzu Kontakt \u00fcber den gew\u00fcnschten Kommunikationsweg aufzunehmen. Eine dar\u00fcber hinausgehende Verarbeitung findet nicht statt. Um Ihre pers\u00f6nlichen Daten besonders zu sch\u00fctzen, ist die Versendung \u00fcber unser Kontaktformular mittels der SSL-Verschl\u00fcsselung eingerichtet. Personenbezogene Daten, die im Rahmen einer allgemeinen Kontaktanfrage \u00fcber das Kontaktformular von uns verarbeitet werden, speichern wir nur so lange, wie dies f\u00fcr die jeweilige Korrespondenz notwendig ist. Personenbezogene Daten, die im Zusammenhang mit einer allgemeinen Anfrage per E-Mail oder per Kontaktformular verarbeitet werden, werden aufgrund einer Einwilligung verarbeitet (Rechtsgrundlage Artikel 6 DSGVO).<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>8. Buchungen auf unserer Internetseite<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">F\u00fcr die Buchungen auf unserer Internetseite nutzen wir ein webbasiertes Onlinebuchungs- und Channelmanagement-System (DIRS21) der TourOnline AG, ans\u00e4ssig in Deutschland, Borsigstr. 26, 73249 Wernau.\u00a0<br \/>N\u00e4heres zu den Datenschutzbestimmungen und Nutzungsbedingungen f\u00fcr DIRS21 erfahren Sie hier:\u00a0<a href=\"http:\/\/www.dirs21.de\/disclaimer\/\" target=\"_blank\" rel=\"noreferrer noopener\">http:\/\/www.dirs21.de\/disclaimer<\/a>\/.<\/p>\n\n<p class=\"wp-block-paragraph\"><br \/>Personenbezogene Daten, die im Zusammenhang mit einer Zimmerbuchung von uns abgefragt werden, werden nur so lange gespeichert, wie dies f\u00fcr die Vertragsabwicklung und eventuelle nachtr\u00e4gliche vertragsbezogene Korrespondenz n\u00f6tig ist bzw. im Falle handels- und\/oder steuerrechtlich relevanter Dokumente, die personenbezogene Daten enthalten, so lange, wie die gesetzlichen Fristen des Handelsgesetzbuches und der Abgabenordnung eine Aufbewahrung dieser Dokumente vorsehen. Personenbezogene Daten, die im Zusammenhang mit einer Zimmerbuchung verarbeitet werden, sind zur Erf\u00fcllung des entsprechenden Vertrags erforderlich (Rechtsgrundlage Artikel 6 DSGVO).<\/p>\n\n<p class=\"wp-block-paragraph\">Scripte und Schriften werden \u2013 sofern m\u00f6glich \u2013 lokal eingebunden. Es werden \u00fcber das Buchungstool verschiedene Scripte eingebunden, worauf wir keinen Einfluss haben.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>9. Bewertungstool<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Zur Verbesserung unserer Leistungen und Steigerung der Qualit\u00e4t, sind wir auf Ihr Feedback angewiesen. Angaben, die Sie uns beim Ausf\u00fcllen des Bewertungstools \u00fcbermitteln, verwenden wir vertraulich.\u00a0<\/p>\n\n<p class=\"wp-block-paragraph\">Zum Schutz der Versendung Ihrer Bewertung \u00fcber das Bewertungstool auf der Internetseite der havenhostel Bremerhaven GmbH nutzen wir den Dienst reCAPTCHA des Unternehmens Google Inc. (Google). Die Abfrage dient der Unterscheidung, ob die Eingabe durch einen Menschen oder missbr\u00e4uchlich durch automatisierte, maschinelle Verarbeitung erfolgt. Die Abfrage schlie\u00dft den Versand der IP-Adresse und ggf. weiterer von Google f\u00fcr den Dienst reCAPTCHA ben\u00f6tigter Daten an Google ein. Zu diesem Zweck wird Ihre Eingabe an Google \u00fcbermittelt und dort weiter verwendet. Durch die Nutzung von reCaptcha erkl\u00e4ren Sie sich damit einverstanden, dass die von Ihnen geleistete Erkennung in die Digitalisierung alter Werke einflie\u00dft. Im Falle der Aktivierung der IP-Anonymisierung auf dieser Webseite wird Ihre IP-Adresse von Google jedoch innerhalb von Mitgliedstaaten der Europ\u00e4ischen Union oder in anderen Vertragsstaaten des Abkommens \u00fcber den Europ\u00e4ischen Wirtschaftsraum zuvor gek\u00fcrzt. Nur in Ausnahmef\u00e4llen wird die volle IP-Adresse an einen Server von Google in den USA \u00fcbertragen und dort gek\u00fcrzt. Im Auftrag des Betreibers dieser Website wird Google diese Informationen benutzen, um Ihre Nutzung dieses Dienstes auszuwerten. Die im Rahmen von reCaptcha von Ihrem Browser \u00fcbermittelte IP-Adresse wird nicht mit anderen Daten von Google zusammengef\u00fchrt. F\u00fcr diese Daten gelten die abweichenden Datenschutzbestimmungen des Unternehmens Google. Weitere Informationen zu den Datenschutzrichtlinien von Google finden Sie unter:\u00a0<a href=\"https:\/\/www.google.com\/intl\/de\/policies\/privacy\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.google.com\/intl\/de\/policies\/privacy\/<\/a>\u00a0.<\/p>\n\n<p class=\"wp-block-paragraph\">Personenbezogene Daten, die durch die Abgabe Ihrer Bewertung verarbeitet werden, werden aufgrund einer Einwilligung verarbeitet (Rechtsgrundlage Artikel 6 DSGVO).\u00a0<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>10. Google Maps<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Die Einbindung von Google Maps auf der Internetseite der havenhostel Bremerhaven GmbH erfolgt \u00fcber ein iFrame (HTML-Element), um geographische Informationen visuell darzustellen. Betreiber von Google Maps ist Google Inc., ans\u00e4ssig in den USA, CA 94043, 1600 Amphitheatre Parkway, Mountain View.<\/p>\n\n<p class=\"wp-block-paragraph\">Bei der Nutzung von Google Maps werden von Google auch Daten \u00fcber die Nutzung der Kartenfunktionen durch Besucher erhoben, verarbeitet und genutzt. Durch die Nutzung von Google Maps k\u00f6nnen Informationen \u00fcber Ihre Benutzung dieser Website (einschlie\u00dflich Ihrer IP-Adresse) an einen Server von Google in den USA \u00fcbertragen und dort gespeichert werden.<\/p>\n\n<p class=\"wp-block-paragraph\">Sie haben die M\u00f6glichkeit, den Service von Google Maps auf einfache Art und Weise zu deaktivieren und somit den Datentransfer an Google zu verhindern: Deaktivieren Sie dazu JavaScript in Ihrem Browser. Wir weisen Sie jedoch darauf hin, dass Sie in diesem Fall die Kartenanzeige nicht nutzen k\u00f6nnen. Durch die Nutzung dieser Website und das Nichtdeaktivieren der JavaScript-Funktion erkl\u00e4ren Sie Ihr Einverst\u00e4ndnis, dass Sie mit der Bearbeitung der \u00fcber Sie erhobenen Daten durch Google in der zuvor beschriebenen Art und Weise und zu dem zuvor benannten Zweck einverstanden sind.N\u00e4heres zu den Datenschutzbestimmungen und Nutzungsbedingungen f\u00fcr Google Maps erfahren Sie hier:<br \/><a href=\"https:\/\/.www..google.com\/intl.\/de_US\/help\/terms_maps.html\" target=\"_blank\" rel=\"noreferrer noopener\">.www..google.com\/intl.\/de_US\/help\/terms_maps.html<\/a>\u00a0\u00a0<\/p>\n\n<p class=\"wp-block-paragraph\">Daten, die durch die die Einbindung von Google Maps auf der Internetseite der havenhostel Bremerhaven GmbH verarbeitet werden, werden aufgrund des wirtschaftlichen Interesses unseres Unternehmens verarbeitet (Rechtsgrundlage Artikel 6 DSGVO).<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>11. Social Media und Portale\u00a0<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\"><strong>11.1 Facebook<br \/><\/strong>Auf unseren Seiten sind Funktionen des sozialen Netzwerks Facebook, Anbieter Facebook Inc., 1 Hacker Way, Menlo Park, California 94025, USA, per Verlinkung eingebunden. Mit einem Klick auf das Facebook-Symbol werden Sie auf die Facebook-Webseite und auf unser Firmen-Facebook-Profil geleitet. Wir weisen darauf hin, dass wir als Anbieter der Seiten keine Kenntnis vom Inhalt der \u00fcbermittelten Daten sowie deren Nutzung durch Facebook erhalten.<\/p>\n\n<p class=\"wp-block-paragraph\">Weitere Informationen hierzu finden Sie in der Datenschutzerkl\u00e4rung von Facebook unter\u00a0<a href=\"https:\/\/de-de.facebook.com\/policy.php\" target=\"_blank\" rel=\"noreferrer noopener\">de-de.facebook.com\/policy.php<\/a>\u00a0.<\/p>\n\n<p class=\"wp-block-paragraph\">Zweck und Umfang der Datenerhebung und die weitere Verarbeitung und Nutzung der Daten durch die\u00a0 Anbieter\u00a0 auf\u00a0 deren\u00a0 Seiten\u00a0 sowie\u00a0 Ihre\u00a0 diesbez\u00fcglichen\u00a0 Rechte\u00a0 und\u00a0 Einstellungsm\u00f6glichkeiten zum Schutz Ihrer Privatsph\u00e4re entnehmen Sie bitte den Datenschutzhinweisen der Anbieter.<\/p>\n\n<p class=\"wp-block-paragraph\">Bitte beachten Sie hinsichtlich externer Links auch Punkt 15 dieser Datenschutzerkl\u00e4rung.<br \/><br \/><strong>11.2 Twitter<\/strong><br \/>Auf unseren Seiten sind Funktionen des sozialen Netzwerks Twitter, Anbieter Twitter Inc., 1355 Market Street, Suite 900, San Francisco, CA 94103, USA, per Verlinkung eingebunden. Mit einem Klick auf das Twitter-Symbol werden Sie auf die Twitter-Webseite und auf unser Firmen-Twitter-Profil geleitet. Wir weisen darauf hin, dass wir als Anbieter der Seiten keine Kenntnis vom Inhalt der \u00fcbermittelten Daten sowie deren Nutzung durch Twitter erhalten.<\/p>\n\n<p class=\"wp-block-paragraph\">Weitere Informationen hierzu finden Sie in der Datenschutzerkl\u00e4rung von Twitter unter\u00a0<a href=\"https:\/\/twitter.com\/privacy\" target=\"_blank\" rel=\"noreferrer noopener\">twitter.com\/privacy<\/a>.<br \/><br \/>Zweck und Umfang der Datenerhebung und die weitere Verarbeitung und Nutzung der Daten durch die\u00a0 Anbieter\u00a0 auf\u00a0 deren\u00a0 Seiten\u00a0 sowie\u00a0 Ihre\u00a0 diesbez\u00fcglichen\u00a0 Rechte\u00a0 und\u00a0 Einstellungsm\u00f6glichkeiten zum Schutz Ihrer Privatsph\u00e4re entnehmen Sie bitte den Datenschutzhinweisen der Anbieter.<br \/><br \/>Bitte beachten Sie hinsichtlich externer Links auch Punkt 15 dieser Datenschutzerkl\u00e4rung.<br \/><br \/><strong>11.3 Youtube<br \/><\/strong>Unsere Website nutzt das Videoportal der von Google betriebenen Seite YouTube. Betreiber der Seiten ist die YouTube, LLC, 901 Cherry Ave., San Bruno, CA 94066, USA. Auf unserer Seite sind keine Plugins eingerichtet, die Verbindung erfolgt per Verlinkung.<br \/><br \/>Weitere Informationen zum Umgang von Nutzerdaten finden Sie in der Datenschutzerkl\u00e4rung von YouTube unter:\u00a0<a href=\"https:\/\/www.google.de\/intl\/de\/policies\/privacy.\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.google.de\/intl\/de\/policies\/privacy.<\/a>\u00a0<br \/><br \/>Bitte beachten Sie hinsichtlich externer Links auch Punkt 15 dieser Datenschutzerkl\u00e4rung.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>12. Verantwortliche Stelle<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">havenhostel Bremerhaven GmbH<br \/>Dillinger Str. 3, 27578 Bremerhaven<br \/>Tel: 0471\/309 669 \u2013 0<br \/>Mail:\u00a0<a href=\"mailto:datenschutz@havenhostel.de\">datenschutz@havenhostel.de<\/a><\/p>\n\n<p class=\"wp-block-paragraph\"><strong>13. Betriebliche Datenschutzbeauftragte<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Frau Alina Grotel\u00fcschen<br \/>Dillinger Str. 3, 27578 Bremerhaven<br \/>Tel: 0471\/309 666 -47<br \/>Mail:\u00a0<a href=\"mailto:datenschutz@havenhostel.de\">datenschutz@havenhostel.de<\/a>\u00a0<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>14. Haftungsausschluss (Inhalt)<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Wir haben die Inhalte unserer Seiten sorgf\u00e4ltig bearbeitet und \u00fcberpr\u00fcft. F\u00fcr die Richtigkeit, Vollst\u00e4ndigkeit, Aktualit\u00e4t und Qualit\u00e4t der bereitgestellten Informationen \u00fcbernehmen wir keine Gew\u00e4hr. F\u00fcr materielle oder immaterielle Sch\u00e4den aus der Nutzung unserer Informationen und Materialien haften wir nicht, es sei denn, die Fehler wurden von uns vors\u00e4tzlich oder grob fahrl\u00e4ssig verursacht.<br \/>\u00a0<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>15. Externe Links<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Wir bieten Links zu fremden Webseiten Dritter an, auf deren Gestaltung und Inhalt wir weder Einfluss haben, noch diese laufend \u00fcberpr\u00fcfen k\u00f6nnen. F\u00fcr deren Inhalte k\u00f6nnen wir daher keine Haftung \u00fcbernehmen. Hierf\u00fcr sind die jeweiligen Anbieter dieser Seiten selbst verantwortlich. Sollten wir Kenntnis von Rechtsverletzungen erhalten, werden wir die Nutzung dieser rechtswidrigen Inhalte verhindern, sofern uns dies technisch m\u00f6glich und zumutbar ist.Wenn Sie \u00fcber die auf unserer Website bereitgestellten Links auf andere Websites zugreifen, erfassen die Betreiber dieser Websites von Ihnen m\u00f6glicherweise Informationen, die von diesen Betreibern in \u00dcbereinstimmung mit ihren Datenschutzrichtlinien verwendet werden. Diese k\u00f6nnen von unserer Datenschutzerkl\u00e4rung abweichen. Wir empfehlen Ihnen, die auf diesen anderen Websites angegebenen Datenschutzerkl\u00e4rungen zu \u00fcberpr\u00fcfen, um Informationen zu deren Verfahren f\u00fcr die Erfassung, Verwendung und Offenlegung personenbezogener Daten zu erhalten.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>16. Google Analytics<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Diese Website nutzt Funktionen des Webanalysedienstes Google Analytics. Anbieter ist die Google Inc., 1600 Amphitheatre Parkway, Mountain View, CA 94043, USA.<\/p>\n\n<p class=\"wp-block-paragraph\">Google Analytics verwendet so genannte &#8222;Cookies&#8220;. Das sind Textdateien, die auf Ihrem Computer gespeichert werden und die eine Analyse der Benutzung der Website durch Sie erm\u00f6glichen. Die durch den Cookie erzeugten Informationen \u00fcber Ihre Benutzung dieser Website werden in der Regel an einen Server von Google in den USA \u00fcbertragen und dort gespeichert.<\/p>\n\n<p class=\"wp-block-paragraph\">Die Speicherung von Google-Analytics-Cookies erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Die Websitebetreiberin hat ein berechtigtes Interesse an der Analyse des Nutzerverhaltens, um sowohl sein Webangebot als auch seine Werbung zu optimieren.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>IP Anonymisierung<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Wir haben auf dieser Website die Funktion IP-Anonymisierung aktiviert. Dadurch wird Ihre IP-Adresse von Google innerhalb von Mitgliedstaaten der Europ\u00e4ischen Union oder in anderen Vertragsstaaten des Abkommens \u00fcber den Europ\u00e4ischen Wirtschaftsraum vor der \u00dcbermittlung in die USA gek\u00fcrzt. Nur in Ausnahmef\u00e4llen wird die volle IP-Adresse an einen Server von Google in den USA \u00fcbertragen und dort gek\u00fcrzt. Im Auftrag der Betreiberin dieser Website wird Google diese Informationen benutzen, um Ihre Nutzung der Website auszuwerten, um Reports \u00fcber die Websiteaktivit\u00e4ten zusammenzustellen und um weitere mit der Websitenutzung und der Internetnutzung verbundene Dienstleistungen gegen\u00fcber der Websitebetreiberin zu erbringen. Die im Rahmen von Google Analytics von Ihrem Browser \u00fcbermittelte IP-Adresse wird nicht mit anderen Daten von Google zusammengef\u00fchrt.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Browser Plugin<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Sie k\u00f6nnen die Speicherung der Cookies durch eine entsprechende Einstellung Ihrer Browser-Software verhindern; wir weisen Sie jedoch darauf hin, dass Sie in diesem Fall gegebenenfalls nicht s\u00e4mtliche Funktionen dieser Website vollumf\u00e4nglich werden nutzen k\u00f6nnen. Sie k\u00f6nnen dar\u00fcber hinaus die Erfassung der durch den Cookie erzeugten und auf Ihre Nutzung der Website bezogenen Daten (inkl. Ihrer IP-Adresse) an Google sowie die Verarbeitung dieser Daten durch Google verhindern, indem Sie das unter dem folgenden Link verf\u00fcgbare Browser-Plugin herunterladen und installieren:\u00a0<a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de<\/a>.<\/p>\n\n<p class=\"wp-block-paragraph\">Alternativ zum Browser-Add-On oder innerhalb von Browsern auf mobilen Ger\u00e4ten,\u00a0<a>klicken Sie bitte diesen Link<\/a>, um die Erfassung durch Google Analytics innerhalb dieser Website zuk\u00fcnftig zu verhindern (das Opt Out funktioniert nur in dem Browser und nur f\u00fcr diese Domain). Dabei wird ein Opt-Out-Cookie auf Ihrem Ger\u00e4t abgelegt. L\u00f6schen Sie Ihre Cookies in diesem Browser, m\u00fcssen Sie diesen Link erneut klicken.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Widerspruch gegen Datenerfassung<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Sie k\u00f6nnen die Erfassung Ihrer Daten durch Google Analytics verhindern, indem Sie auf folgenden Link klicken. Es wird ein Opt-Out-Cookie gesetzt, der die Erfassung Ihrer Daten bei zuk\u00fcnftigen Besuchen dieser Website verhindert:\u00a0Google Analytics deaktivieren.<\/p>\n\n<p class=\"wp-block-paragraph\">Mehr Informationen zum Umgang mit Nutzerdaten bei Google Analytics finden Sie in der Datenschutzerkl\u00e4rung von Google:\u00a0<a href=\"https:\/\/support.google.com\/analytics\/answer\/6004245?hl=de\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/support.google.com\/analytics\/\u00adanswer\/6004245?hl=de<\/a>.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Auftragsdatenverarbeitung<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Wir haben mit Google einen Vertrag zur Auftragsdatenverarbeitung abgeschlossen und setzen die strengen Vorgaben der deutschen Datenschutzbeh\u00f6rden bei der Nutzung von Google Analytics vollst\u00e4ndig um.<\/p>\n\n<p class=\"wp-block-paragraph\"><strong>Demografische Merkmale bei Google Analytics<\/strong><\/p>\n\n<p class=\"wp-block-paragraph\">Diese Website nutzt die Funktion \u201cdemografische Merkmale\u201d von Google Analytics. Dadurch k\u00f6nnen Berichte erstellt werden, die Aussagen zu Alter, Geschlecht und Interessen der Seitenbesucher enthalten. Diese Daten stammen aus interessenbezogener Werbung von Google sowie aus Besucherdaten von Drittanbietern. Diese Daten k\u00f6nnen keiner bestimmten Person zugeordnet werden. Sie k\u00f6nnen diese Funktion jederzeit \u00fcber die Anzeigeneinstellungen in Ihrem Google-Konto deaktivieren oder die Erfassung Ihrer Daten durch Google Analytics wie im Punkt \u201cWiderspruch gegen Datenerfassung\u201d dargestellt generell untersagen.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b0cccdb elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b0cccdb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1fc680e\" data-id=\"1fc680e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff7d850 elementor-widget elementor-widget-text-editor\" data-id=\"ff7d850\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h1>Datenschutz\u00aderkl\u00e4rung<\/h1>\n<div>&nbsp;<\/div>\n<h2>1. Datenschutz auf einen Blick<\/h2>\n<h3>Allgemeine Hinweise<\/h3>\n<p>Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie diese Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung.<\/p>\n<h3>Datenerfassung auf dieser Website<\/h3>\n<h4>Wer ist verantwortlich f\u00fcr die Datenerfassung auf dieser Website?<\/h4>\n<p>Die Datenverarbeitung auf dieser Website erfolgt durch den Websitebetreiber. Dessen Kontaktdaten k\u00f6nnen Sie dem Abschnitt \u201eHinweis zur Verantwortlichen Stelle\u201c in dieser Datenschutzerkl\u00e4rung entnehmen.<\/p>\n<h4>Wie erfassen wir Ihre Daten?<\/h4>\n<p>Ihre Daten werden zum einen dadurch erhoben, dass Sie uns diese mitteilen. Hierbei kann es sich z. B. um Daten handeln, die Sie in ein Kontaktformular eingeben.<\/p>\n<p>Andere Daten werden automatisch oder nach Ihrer Einwilligung beim Besuch der Website durch unsere IT-Systeme erfasst. Das sind vor allem technische Daten (z. B. Internetbrowser, Betriebssystem oder Uhrzeit des Seitenaufrufs). Die Erfassung dieser Daten erfolgt automatisch, sobald Sie diese Website betreten.<\/p>\n<h4>Wof\u00fcr nutzen wir Ihre Daten?<\/h4>\n<p>Ein Teil der Daten wird erhoben, um eine fehlerfreie Bereitstellung der Website zu gew\u00e4hrleisten. Andere Daten k\u00f6nnen zur Analyse Ihres Nutzerverhaltens verwendet werden.<\/p>\n<h4>Welche Rechte haben Sie bez\u00fcglich Ihrer Daten?<\/h4>\n<p>Sie haben jederzeit das Recht, unentgeltlich Auskunft \u00fcber Herkunft, Empf\u00e4nger und Zweck Ihrer gespeicherten personenbezogenen Daten zu erhalten. Sie haben au\u00dferdem ein Recht, die Berichtigung oder L\u00f6schung dieser Daten zu verlangen. Wenn Sie eine Einwilligung zur Datenverarbeitung erteilt haben, k\u00f6nnen Sie diese Einwilligung jederzeit f\u00fcr die Zukunft widerrufen. Au\u00dferdem haben Sie das Recht, unter bestimmten Umst\u00e4nden die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen. Des Weiteren steht Ihnen ein Beschwerderecht bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde zu.<\/p>\n<p>Hierzu sowie zu weiteren Fragen zum Thema Datenschutz k\u00f6nnen Sie sich jederzeit an uns wenden.<\/p>\n<h2>2. Hosting<\/h2>\n<h3>Externes Hosting<\/h3>\n<p>Diese Website wird bei einem externen Dienstleister gehostet (Hoster). Die personenbezogenen Daten, die auf dieser Website erfasst werden, werden auf den Servern des Hosters gespeichert. Hierbei kann es sich v. a. um IP-Adressen, Kontaktanfragen, Meta- und Kommunikationsdaten, Vertragsdaten, Kontaktdaten, Namen, Websitezugriffe und sonstige Daten, die \u00fcber eine Website generiert werden, handeln.<\/p>\n<p>Der Einsatz des Hosters erfolgt zum Zwecke der Vertragserf\u00fcllung gegen\u00fcber unseren potenziellen und bestehenden Kunden (Art. 6 Abs. 1 lit. b DSGVO) und im Interesse einer sicheren, schnellen und effizienten Bereitstellung unseres Online-Angebots durch einen professionellen Anbieter (Art. 6 Abs. 1 lit. f DSGVO).<\/p>\n<p>Unser Hoster wird Ihre Daten nur insoweit verarbeiten, wie dies zur Erf\u00fcllung seiner Leistungspflichten erforderlich ist und unsere Weisungen in Bezug auf diese Daten befolgen.<\/p>\n<p>Wir setzen folgenden Hoster ein:<\/p><p><strong>netactive GmbH<\/strong><br>Barkhausenstra\u00dfe 6<br>27568 Bremerhaven<\/p>\n<p>Tel.: 0471 30 99 66 \u2013 0<br>Fax: 0471 30 99 66 \u2013 30<br>info@netactive.de<\/p><h4>Auftragsverarbeitung<\/h4>\n<p>Wir haben einen Vertrag \u00fcber Auftragsverarbeitung (AVV) mit dem oben genannten Anbieter geschlossen. Hierbei handelt es sich um einen datenschutzrechtlich vorgeschriebenen Vertrag, der gew\u00e4hrleistet, dass dieser die personenbezogenen Daten unserer Websitebesucher nur nach unseren Weisungen und unter Einhaltung der DSGVO verarbeitet.<\/p>\n<h2>3. Allgemeine Hinweise und Pflicht\u00adinformationen<\/h2>\n<h3>Datenschutz<\/h3>\n<p>Die Betreiber dieser Seiten nehmen den Schutz Ihrer pers\u00f6nlichen Daten sehr ernst. Wir behandeln Ihre personenbezogenen Daten vertraulich und entsprechend den gesetzlichen Datenschutzvorschriften sowie dieser Datenschutzerkl\u00e4rung.<\/p>\n<p>Wenn Sie diese Website benutzen, werden verschiedene personenbezogene Daten erhoben. Personenbezogene Daten sind Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Die vorliegende Datenschutzerkl\u00e4rung erl\u00e4utert, welche Daten wir erheben und wof\u00fcr wir sie nutzen. Sie erl\u00e4utert auch, wie und zu welchem Zweck das geschieht.<\/p>\n<p>Wir weisen darauf hin, dass die Daten\u00fcbertragung im Internet (z. B. bei der Kommunikation per E-Mail) Sicherheitsl\u00fccken aufweisen kann. Ein l\u00fcckenloser Schutz der Daten vor dem Zugriff durch Dritte ist nicht m\u00f6glich.<\/p>\n<h3>Hinweis zur verantwortlichen Stelle<\/h3>\n<p>Die verantwortliche Stelle f\u00fcr die Datenverarbeitung auf dieser Website ist:<\/p>\n<p>havenhostel Bremerhaven GmbH<br><a href=\"https:\/\/www.google.de\/maps\/place\/havenhostel+Bremerhaven\/@53.5595417,8.5649908,17z\/data=!4m7!1m4!3m3!1s0x47b6b0ff5d5c9035:0x63c21cafe197310e!2shavenhostel+Bremerhaven!3b1!3m1!1s0x47b6b0ff5d5c9035:0x63c21cafe197310e\" target=\"_blank\" rel=\"noreferrer noopener\">B\u00fcrgermeister-Smidt-Stra\u00dfe 209<br>27568 Bremerhaven<\/a><\/p>\n<p>E-Mail: <a href=\"mailto:info@havenhostel.de\">info@havenhostel.de<\/a><\/p>\n<p>Verantwortliche Stelle ist die nat\u00fcrliche oder juristische Person, die allein oder gemeinsam mit anderen \u00fcber die Zwecke und Mittel der Verarbeitung von personenbezogenen Daten (z. B. Namen, E-Mail-Adressen o. \u00c4.) entscheidet.<\/p>\n<h3>Speicherdauer<\/h3>\n<p>Soweit innerhalb dieser Datenschutzerkl\u00e4rung keine speziellere Speicherdauer genannt wurde, verbleiben Ihre personenbezogenen Daten bei uns, bis der Zweck f\u00fcr die Datenverarbeitung entf\u00e4llt. Wenn Sie ein berechtigtes L\u00f6schersuchen geltend machen oder eine Einwilligung zur Datenverarbeitung widerrufen, werden Ihre Daten gel\u00f6scht, sofern wir keine anderen rechtlich zul\u00e4ssigen Gr\u00fcnde f\u00fcr die Speicherung Ihrer personenbezogenen Daten haben (z. B. steuer- oder handelsrechtliche Aufbewahrungsfristen); im letztgenannten Fall erfolgt die L\u00f6schung nach Fortfall dieser Gr\u00fcnde.<\/p>\n<h3>Datenschutz\u00adbeauftragter<\/h3>\n<p>Wir haben f\u00fcr unser Unternehmen einen Datenschutzbeauftragten bestellt.<\/p>\n<p>havenhostel Bremerhaven GmbH<br>Frau Alina Grotel\u00fcschen<br>Dillinger Str. 3<br>27578 Bremerhaven<\/p>\n<p>E-Mail: <a href=\"mailto:datenschutz@havenhostel.de\">datenschutz@havenhostel.de<\/a><\/p>\n<h3>Hinweis zur Datenweitergabe in die USA und sonstige Drittstaaten<\/h3>\n<p>Wir verwenden unter anderem Tools von Unternehmen mit Sitz in den USA oder sonstigen datenschutzrechtlich nicht sicheren Drittstaaten. Wenn diese Tools aktiv sind, k\u00f6nnen Ihre personenbezogene Daten in diese Drittstaaten \u00fcbertragen und dort verarbeitet werden. Wir weisen darauf hin, dass in diesen L\u00e4ndern kein mit der EU vergleichbares Datenschutzniveau garantiert werden kann. Beispielsweise sind US-Unternehmen dazu verpflichtet, personenbezogene Daten an Sicherheitsbeh\u00f6rden herauszugeben, ohne dass Sie als Betroffener hiergegen gerichtlich vorgehen k\u00f6nnten. Es kann daher nicht ausgeschlossen werden, dass US-Beh\u00f6rden (z. B. Geheimdienste) Ihre auf US-Servern befindlichen Daten zu \u00dcberwachungszwecken verarbeiten, auswerten und dauerhaft speichern. Wir haben auf diese Verarbeitungst\u00e4tigkeiten keinen Einfluss.<\/p>\n<h3>Widerruf Ihrer Einwilligung zur Datenverarbeitung<\/h3>\n<p>Viele Datenverarbeitungsvorg\u00e4nge sind nur mit Ihrer ausdr\u00fccklichen Einwilligung m\u00f6glich. Sie k\u00f6nnen eine bereits erteilte Einwilligung jederzeit widerrufen. Die Rechtm\u00e4\u00dfigkeit der bis zum Widerruf erfolgten Datenverarbeitung bleibt vom Widerruf unber\u00fchrt.<\/p>\n<h3>Widerspruchsrecht gegen die Datenerhebung in besonderen F\u00e4llen sowie gegen Direktwerbung (Art. 21 DSGVO)<\/h3>\n<p>WENN DIE DATENVERARBEITUNG AUF GRUNDLAGE VON ART. 6 ABS. 1 LIT. E ODER F DSGVO ERFOLGT, HABEN SIE JEDERZEIT DAS RECHT, AUS GR\u00dcNDEN, DIE SICH AUS IHRER BESONDEREN SITUATION ERGEBEN, GEGEN DIE VERARBEITUNG IHRER PERSONENBEZOGENEN DATEN WIDERSPRUCH EINZULEGEN; DIES GILT AUCH F\u00dcR EIN AUF DIESE BESTIMMUNGEN GEST\u00dcTZTES PROFILING. DIE JEWEILIGE RECHTSGRUNDLAGE, AUF DENEN EINE VERARBEITUNG BERUHT, ENTNEHMEN SIE DIESER DATENSCHUTZERKL\u00c4RUNG. WENN SIE WIDERSPRUCH EINLEGEN, WERDEN WIR IHRE BETROFFENEN PERSONENBEZOGENEN DATEN NICHT MEHR VERARBEITEN, ES SEI DENN, WIR K\u00d6NNEN ZWINGENDE SCHUTZW\u00dcRDIGE GR\u00dcNDE F\u00dcR DIE VERARBEITUNG NACHWEISEN, DIE IHRE INTERESSEN, RECHTE UND FREIHEITEN \u00dcBERWIEGEN ODER DIE VERARBEITUNG DIENT DER GELTENDMACHUNG, AUS\u00dcBUNG ODER VERTEIDIGUNG VON RECHTSANSPR\u00dcCHEN (WIDERSPRUCH NACH ART. 21 ABS. 1 DSGVO).<\/p>\n<p>WERDEN IHRE PERSONENBEZOGENEN DATEN VERARBEITET, UM DIREKTWERBUNG ZU BETREIBEN, SO HABEN SIE DAS RECHT, JEDERZEIT WIDERSPRUCH GEGEN DIE VERARBEITUNG SIE BETREFFENDER PERSONENBEZOGENER DATEN ZUM ZWECKE DERARTIGER WERBUNG EINZULEGEN; DIES GILT AUCH F\u00dcR DAS PROFILING, SOWEIT ES MIT SOLCHER DIREKTWERBUNG IN VERBINDUNG STEHT. WENN SIE WIDERSPRECHEN, WERDEN IHRE PERSONENBEZOGENEN DATEN ANSCHLIESSEND NICHT MEHR ZUM ZWECKE DER DIREKTWERBUNG VERWENDET (WIDERSPRUCH NACH ART. 21 ABS. 2 DSGVO).<\/p>\n<h3>Beschwerde\u00adrecht bei der zust\u00e4ndigen Aufsichts\u00adbeh\u00f6rde<\/h3>\n<p>Im Falle von Verst\u00f6\u00dfen gegen die DSGVO steht den Betroffenen ein Beschwerderecht bei einer Aufsichtsbeh\u00f6rde, insbesondere in dem Mitgliedstaat ihres gew\u00f6hnlichen Aufenthalts, ihres Arbeitsplatzes oder des Orts des mutma\u00dflichen Versto\u00dfes zu. Das Beschwerderecht besteht unbeschadet anderweitiger verwaltungsrechtlicher oder gerichtlicher Rechtsbehelfe.<\/p>\n<h3>Recht auf Daten\u00ad\u00fcbertrag\u00adbarkeit<\/h3>\n<p>Sie haben das Recht, Daten, die wir auf Grundlage Ihrer Einwilligung oder in Erf\u00fcllung eines Vertrags automatisiert verarbeiten, an sich oder an einen Dritten in einem g\u00e4ngigen, maschinenlesbaren Format aush\u00e4ndigen zu lassen. Sofern Sie die direkte \u00dcbertragung der Daten an einen anderen Verantwortlichen verlangen, erfolgt dies nur, soweit es technisch machbar ist.<\/p>\n<h3>SSL- bzw. TLS-Verschl\u00fcsselung<\/h3>\n<p>Diese Seite nutzt aus Sicherheitsgr\u00fcnden und zum Schutz der \u00dcbertragung vertraulicher Inhalte, wie zum Beispiel Bestellungen oder Anfragen, die Sie an uns als Seitenbetreiber senden, eine SSL- bzw. TLS-Verschl\u00fcsselung. Eine verschl\u00fcsselte Verbindung erkennen Sie daran, dass die Adresszeile des Browsers von \u201ehttp:\/\/\u201c auf \u201ehttps:\/\/\u201c wechselt und an dem Schloss-Symbol in Ihrer Browserzeile.<\/p>\n<p>Wenn die SSL- bzw. TLS-Verschl\u00fcsselung aktiviert ist, k\u00f6nnen die Daten, die Sie an uns \u00fcbermitteln, nicht von Dritten mitgelesen werden.<\/p>\n<h3>Auskunft, L\u00f6schung und Berichtigung<\/h3>\n<p>Sie haben im Rahmen der geltenden gesetzlichen Bestimmungen jederzeit das Recht auf unentgeltliche Auskunft \u00fcber Ihre gespeicherten personenbezogenen Daten, deren Herkunft und Empf\u00e4nger und den Zweck der Datenverarbeitung und ggf. ein Recht auf Berichtigung oder L\u00f6schung dieser Daten. Hierzu sowie zu weiteren Fragen zum Thema personenbezogene Daten k\u00f6nnen Sie sich jederzeit an uns wenden.<\/p>\n<h3>Recht auf Einschr\u00e4nkung der Verarbeitung<\/h3>\n<p>Sie haben das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen. Hierzu k\u00f6nnen Sie sich jederzeit an uns wenden. Das Recht auf Einschr\u00e4nkung der Verarbeitung besteht in folgenden F\u00e4llen:<\/p>\n<ul>\n<li>Wenn Sie die Richtigkeit Ihrer bei uns gespeicherten personenbezogenen Daten bestreiten, ben\u00f6tigen wir in der Regel Zeit, um dies zu \u00fcberpr\u00fcfen. F\u00fcr die Dauer der Pr\u00fcfung haben Sie das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/li>\n<li>Wenn die Verarbeitung Ihrer personenbezogenen Daten unrechtm\u00e4\u00dfig geschah\/geschieht, k\u00f6nnen Sie statt der L\u00f6schung die Einschr\u00e4nkung der Datenverarbeitung verlangen.<\/li>\n<li>Wenn wir Ihre personenbezogenen Daten nicht mehr ben\u00f6tigen, Sie sie jedoch zur Aus\u00fcbung, Verteidigung oder Geltendmachung von Rechtsanspr\u00fcchen ben\u00f6tigen, haben Sie das Recht, statt der L\u00f6schung die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/li>\n<li>Wenn Sie einen Widerspruch nach Art. 21 Abs. 1 DSGVO eingelegt haben, muss eine Abw\u00e4gung zwischen Ihren und unseren Interessen vorgenommen werden. Solange noch nicht feststeht, wessen Interessen \u00fcberwiegen, haben Sie das Recht, die Einschr\u00e4nkung der Verarbeitung Ihrer personenbezogenen Daten zu verlangen.<\/li>\n<\/ul>\n<p>Wenn Sie die Verarbeitung Ihrer personenbezogenen Daten eingeschr\u00e4nkt haben, d\u00fcrfen diese Daten \u2013 von ihrer Speicherung abgesehen \u2013 nur mit Ihrer Einwilligung oder zur Geltendmachung, Aus\u00fcbung oder Verteidigung von Rechtsanspr\u00fcchen oder zum Schutz der Rechte einer anderen nat\u00fcrlichen oder juristischen Person oder aus Gr\u00fcnden eines wichtigen \u00f6ffentlichen Interesses der Europ\u00e4ischen Union oder eines Mitgliedstaats verarbeitet werden.<\/p>\n<h2>4. Datenerfassung auf dieser Website<\/h2>\n<h3>Cookies<\/h3>\n<p>Unsere Internetseiten verwenden so genannte \u201eCookies\u201c. Cookies sind kleine Textdateien und richten auf Ihrem Endger\u00e4t keinen Schaden an. Sie werden entweder vor\u00fcbergehend f\u00fcr die Dauer einer Sitzung (Session-Cookies) oder dauerhaft (permanente Cookies) auf Ihrem Endger\u00e4t gespeichert. Session-Cookies werden nach Ende Ihres Besuchs automatisch gel\u00f6scht. Permanente Cookies bleiben auf Ihrem Endger\u00e4t gespeichert, bis Sie diese selbst l\u00f6schen oder eine automatische L\u00f6schung durch Ihren Webbrowser erfolgt.<\/p>\n<p>Teilweise k\u00f6nnen auch Cookies von Drittunternehmen auf Ihrem Endger\u00e4t gespeichert werden, wenn Sie unsere Seite betreten (Third-Party-Cookies). Diese erm\u00f6glichen uns oder Ihnen die Nutzung bestimmter Dienstleistungen des Drittunternehmens (z. B. Cookies zur Abwicklung von Zahlungsdienstleistungen).<\/p>\n<p>Cookies haben verschiedene Funktionen. Zahlreiche Cookies sind technisch notwendig, da bestimmte Websitefunktionen ohne diese nicht funktionieren w\u00fcrden (z. B. die Warenkorbfunktion oder die Anzeige von Videos). Andere Cookies dienen dazu, das Nutzerverhalten auszuwerten oder Werbung anzuzeigen.<\/p>\n<p>Cookies, die zur Durchf\u00fchrung des elektronischen Kommunikationsvorgangs (notwendige Cookies) oder zur Bereitstellung bestimmter, von Ihnen erw\u00fcnschter Funktionen (funktionale Cookies, z. B. f\u00fcr die Warenkorbfunktion) oder zur Optimierung der Website (z. B. Cookies zur Messung des Webpublikums) erforderlich sind, werden auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO gespeichert, sofern keine andere Rechtsgrundlage angegeben wird. Der Websitebetreiber hat ein berechtigtes Interesse an der Speicherung von Cookies zur technisch fehlerfreien und optimierten Bereitstellung seiner Dienste. Sofern eine Einwilligung zur Speicherung von Cookies abgefragt wurde, erfolgt die Speicherung der betreffenden Cookies ausschlie\u00dflich auf Grundlage dieser Einwilligung (Art. 6 Abs. 1 lit. a DSGVO); die Einwilligung ist jederzeit widerrufbar.<\/p>\n<p>Sie k\u00f6nnen Ihren Browser so einstellen, dass Sie \u00fcber das Setzen von Cookies informiert werden und Cookies nur im Einzelfall erlauben, die Annahme von Cookies f\u00fcr bestimmte F\u00e4lle oder generell ausschlie\u00dfen sowie das automatische L\u00f6schen der Cookies beim Schlie\u00dfen des Browsers aktivieren. Bei der Deaktivierung von Cookies kann die Funktionalit\u00e4t dieser Website eingeschr\u00e4nkt sein.<\/p>\n<p>Soweit Cookies von Drittunternehmen oder zu Analysezwecken eingesetzt werden, werden wir Sie hier\u00fcber im Rahmen dieser Datenschutzerkl\u00e4rung gesondert informieren und ggf. eine Einwilligung abfragen.<\/p>\n<h3>Einwilligung mit Usercentrics<\/h3>\n<p>Diese Website nutzt die Consent-Technologie von Usercentrics, um Ihre Einwilligung zur Speicherung bestimmter Cookies auf Ihrem Endger\u00e4t oder zum Einsatz bestimmter Technologien einzuholen und diese datenschutzkonform zu dokumentieren. Anbieter dieser Technologie ist die Usercentrics GmbH, Sendlinger Stra\u00dfe 7, 80331 M\u00fcnchen, Website: <a href=\"https:\/\/usercentrics.com\/de\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/usercentrics.com\/de\/<\/a> (im Folgenden \u201eUsercentrics\u201c).<\/p>\n<p>Wenn Sie unsere Website betreten, werden folgende personenbezogene Daten an Usercentrics \u00fcbertragen:<\/p>\n<ul>\n<li>Ihre Einwilligung(en) bzw. der Widerruf Ihrer Einwilligung(en)<\/li>\n<li>Ihre IP-Adresse<\/li>\n<li>Informationen \u00fcber Ihren Browser<\/li>\n<li>Informationen \u00fcber Ihr Endger\u00e4t<\/li>\n<li>Zeitpunkt Ihres Besuchs auf der Website<\/li>\n<\/ul>\n<p>Des Weiteren speichert Usercentrics ein Cookie in Ihrem Browser, um Ihnen die erteilten Einwilligungen bzw. deren Widerruf zuordnen zu k\u00f6nnen. Die so erfassten Daten werden gespeichert, bis Sie uns zur L\u00f6schung auffordern, das Usercentrics-Cookie selbst l\u00f6schen oder der Zweck f\u00fcr die Datenspeicherung entf\u00e4llt. Zwingende gesetzliche Aufbewahrungspflichten bleiben unber\u00fchrt.<\/p>\n<p>Der Einsatz von Usercentrics erfolgt, um die gesetzlich vorgeschriebenen Einwilligungen f\u00fcr den Einsatz bestimmter Technologien einzuholen. Rechtsgrundlage hierf\u00fcr ist Art. 6 Abs. 1 lit. c DSGVO.<\/p>\n<h4>Auftragsverarbeitung<\/h4>\n<p>Wir haben einen Vertrag \u00fcber Auftragsverarbeitung (AVV) mit dem oben genannten Anbieter geschlossen. Hierbei handelt es sich um einen datenschutzrechtlich vorgeschriebenen Vertrag, der gew\u00e4hrleistet, dass dieser die personenbezogenen Daten unserer Websitebesucher nur nach unseren Weisungen und unter Einhaltung der DSGVO verarbeitet.<\/p>\n<h3>Kontaktformular<\/h3>\n<p>Wenn Sie uns per Kontaktformular Anfragen zukommen lassen, werden Ihre Angaben aus dem Anfrageformular inklusive der von Ihnen dort angegebenen Kontaktdaten zwecks Bearbeitung der Anfrage und f\u00fcr den Fall von Anschlussfragen bei uns gespeichert. Diese Daten geben wir nicht ohne Ihre Einwilligung weiter.<\/p>\n<p>Die Verarbeitung dieser Daten erfolgt auf Grundlage von Art. 6 Abs. 1 lit. b DSGVO, sofern Ihre Anfrage mit der Erf\u00fcllung eines Vertrags zusammenh\u00e4ngt oder zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich ist. In allen \u00fcbrigen F\u00e4llen beruht die Verarbeitung auf unserem berechtigten Interesse an der effektiven Bearbeitung der an uns gerichteten Anfragen (Art. 6 Abs. 1 lit. f DSGVO) oder auf Ihrer Einwilligung (Art. 6 Abs. 1 lit. a DSGVO) sofern diese abgefragt wurde.<\/p>\n<p>Die von Ihnen im Kontaktformular eingegebenen Daten verbleiben bei uns, bis Sie uns zur L\u00f6schung auffordern, Ihre Einwilligung zur Speicherung widerrufen oder der Zweck f\u00fcr die Datenspeicherung entf\u00e4llt (z. B. nach abgeschlossener Bearbeitung Ihrer Anfrage). Zwingende gesetzliche Bestimmungen \u2013 insbesondere Aufbewahrungsfristen \u2013 bleiben unber\u00fchrt.<\/p>\n<h3>Anfrage per E-Mail, Telefon oder Telefax<\/h3>\n<p>Wenn Sie uns per E-Mail, Telefon oder Telefax kontaktieren, wird Ihre Anfrage inklusive aller daraus hervorgehenden personenbezogenen Daten (Name, Anfrage) zum Zwecke der Bearbeitung Ihres Anliegens bei uns gespeichert und verarbeitet. Diese Daten geben wir nicht ohne Ihre Einwilligung weiter.<\/p>\n<p>Die Verarbeitung dieser Daten erfolgt auf Grundlage von Art. 6 Abs. 1 lit. b DSGVO, sofern Ihre Anfrage mit der Erf\u00fcllung eines Vertrags zusammenh\u00e4ngt oder zur Durchf\u00fchrung vorvertraglicher Ma\u00dfnahmen erforderlich ist. In allen \u00fcbrigen F\u00e4llen beruht die Verarbeitung auf unserem berechtigten Interesse an der effektiven Bearbeitung der an uns gerichteten Anfragen (Art. 6 Abs. 1 lit. f DSGVO) oder auf Ihrer Einwilligung (Art. 6 Abs. 1 lit. a DSGVO) sofern diese abgefragt wurde.<\/p>\n<p>Die von Ihnen an uns per Kontaktanfragen \u00fcbersandten Daten verbleiben bei uns, bis Sie uns zur L\u00f6schung auffordern, Ihre Einwilligung zur Speicherung widerrufen oder der Zweck f\u00fcr die Datenspeicherung entf\u00e4llt (z. B. nach abgeschlossener Bearbeitung Ihres Anliegens). Zwingende gesetzliche Bestimmungen \u2013 insbesondere gesetzliche Aufbewahrungsfristen \u2013 bleiben unber\u00fchrt.<\/p>\n<h2>5. Soziale Medien<\/h2>\n<h3>Instagram Plugin<\/h3>\n<p>Auf dieser Website sind Funktionen des Dienstes Instagram eingebunden. Diese Funktionen werden angeboten durch die Meta Platforms Ireland Limited, 4 Grand Canal Square, Grand Canal Harbour, Dublin 2, Irland integriert.<\/p>\n<p>Wenn Sie in Ihrem Instagram-Account eingeloggt sind, k\u00f6nnen Sie durch Anklicken des Instagram-Buttons die Inhalte dieser Website mit Ihrem Instagram-Profil verlinken. Dadurch kann Instagram den Besuch dieser Website Ihrem Benutzerkonto zuordnen. Wir weisen darauf hin, dass wir als Anbieter der Seiten keine Kenntnis vom Inhalt der \u00fcbermittelten Daten sowie deren Nutzung durch Instagram erhalten.<\/p>\n<p>Die Speicherung und Analyse der Daten erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Der Websitebetreiber hat ein berechtigtes Interesse an einer m\u00f6glichst umfangreichen Sichtbarkeit in den Sozialen Medien. Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO; die Einwilligung ist jederzeit widerrufbar.<\/p>\n<p>Soweit mit Hilfe des hier beschriebenen Tools personenbezogene Daten auf unserer Website erfasst und an Facebook bzw. Instagram weitergeleitet werden, sind wir und die Meta Platforms Ireland Limited, 4 Grand Canal Square, Grand Canal Harbour, Dublin 2, Irland gemeinsam f\u00fcr diese Datenverarbeitung verantwortlich (Art. 26 DSGVO). Die gemeinsame Verantwortlichkeit beschr\u00e4nkt sich dabei ausschlie\u00dflich auf die Erfassung der Daten und deren Weitergabe an Facebook bzw. Instagram. Die nach der Weiterleitung erfolgende Verarbeitung durch Facebook bzw. Instagram ist nicht Teil der gemeinsamen Verantwortung. Die uns gemeinsam obliegenden Verpflichtungen wurden in einer Vereinbarung \u00fcber gemeinsame Verarbeitung festgehalten. Den Wortlaut der Vereinbarung finden Sie unter: <a href=\"https:\/\/www.facebook.com\/legal\/controller_addendum\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/legal\/controller_addendum<\/a>. Laut dieser Vereinbarung sind wir f\u00fcr die Erteilung der Datenschutzinformationen beim Einsatz des Facebook- bzw. Instagram-Tools und f\u00fcr die datenschutzrechtlich sichere Implementierung des Tools auf unserer Website verantwortlich. F\u00fcr die Datensicherheit der Facebook bzw. Instagram-Produkte ist Facebook verantwortlich. Betroffenenrechte (z. B. Auskunftsersuchen) hinsichtlich der bei Facebook bzw. Instagram verarbeiteten Daten k\u00f6nnen Sie direkt bei Facebook geltend machen. Wenn Sie die Betroffenenrechte bei uns geltend machen, sind wir verpflichtet, diese an Facebook weiterzuleiten.<\/p>\n<p>Die Daten\u00fcbertragung in die USA wird auf die Standardvertragsklauseln der EU-Kommission gest\u00fctzt. Details finden Sie hier: <a href=\"https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum<\/a>, <a href=\"https:\/\/help.instagram.com\/519522125107875\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/help.instagram.com\/519522125107875<\/a> und <a href=\"https:\/\/de-de.facebook.com\/help\/566994660333381\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/de-de.facebook.com\/help\/566994660333381<\/a>.<\/p>\n<p>Weitere Informationen hierzu finden Sie in der Datenschutzerkl\u00e4rung von Instagram: <a href=\"https:\/\/instagram.com\/about\/legal\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/instagram.com\/about\/legal\/privacy\/<\/a>.<\/p>\n<h2>6. Analyse-Tools und Werbung<\/h2>\n<h3>Google Tag Manager<\/h3>\n<p>Wir setzen den Google Tag Manager ein. Anbieter ist die Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irland.<\/p>\n<p>Der Google Tag Manager ist ein Tool, mit dessen Hilfe wir Tracking- oder Statistik-Tools und andere Technologien auf unserer Website einbinden k\u00f6nnen. Der Google Tag Manager selbst erstellt keine Nutzerprofile, speichert keine Cookies und nimmt keine eigenst\u00e4ndigen Analysen vor. Er dient lediglich der Verwaltung und Ausspielung der \u00fcber ihn eingebundenen Tools. Der Google Tag Manager erfasst jedoch Ihre IP-Adresse, die auch an das Mutterunternehmen von Google in die Vereinigten Staaten \u00fcbertragen werden kann.<\/p>\n<p>Der Einsatz des Google Tag Managers erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Der Websitebetreiber hat ein berechtigtes Interesse an einer schnellen und unkomplizierten Einbindung und Verwaltung verschiedener Tools auf seiner Website. Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO; die Einwilligung ist jederzeit widerrufbar.<\/p>\n<h3>Google Analytics<\/h3>\n<p>Diese Website nutzt Funktionen des Webanalysedienstes Google Analytics. Anbieter ist die Google Ireland Limited (\u201eGoogle\u201c), Gordon House, Barrow Street, Dublin 4, Irland.<\/p>\n<p>Google Analytics erm\u00f6glicht es dem Websitebetreiber, das Verhalten der Websitebesucher zu analysieren. Hierbei erh\u00e4lt der Websitebetreiber verschiedene Nutzungsdaten, wie z.&nbsp;B. Seitenaufrufe, Verweildauer, verwendete Betriebssysteme und Herkunft des Nutzers. Diese Daten werden von Google ggf. in einem Profil zusammengefasst, das dem jeweiligen Nutzer bzw. dessen Endger\u00e4t zugeordnet ist.<\/p>\n<p>Des Weiteren k\u00f6nnen wir mit Google Analytics u.&nbsp;a. Ihre Maus- und Scrollbewegungen und Klicks aufzeichnen. Ferner verwendet Google Analytics verschiedene Modellierungsans\u00e4tze, um die erfassten Datens\u00e4tze zu erg\u00e4nzen und setzt Machine Learning-Technologien bei der Datenanalyse ein.<\/p>\n<p>Google Analytics verwendet Technologien, die die Wiedererkennung des Nutzers zum Zwecke der Analyse des Nutzerverhaltens erm\u00f6glichen (z.&nbsp;B. Cookies oder Device-Fingerprinting). Die von Google erfassten Informationen \u00fcber die Benutzung dieser Website werden in der Regel an einen Server von Google in den USA \u00fcbertragen und dort gespeichert.<\/p>\n<p>Die Nutzung dieses Analyse-Tools erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Der Websitebetreiber hat ein berechtigtes Interesse an der Analyse des Nutzerverhaltens, um sowohl sein Webangebot als auch seine Werbung zu optimieren. Sofern eine entsprechende Einwilligung abgefragt wurde (z.&nbsp;B. eine Einwilligung zur Speicherung von Cookies), erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO; die Einwilligung ist jederzeit widerrufbar.<\/p>\n<p>Die Daten\u00fcbertragung in die USA wird auf die Standardvertragsklauseln der EU-Kommission gest\u00fctzt. Details finden Sie hier: <a href=\"https:\/\/privacy.google.com\/businesses\/controllerterms\/mccs\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/privacy.google.com\/businesses\/controllerterms\/mccs\/<\/a>.<\/p>\n<h4>Browser Plugin<\/h4>\n<p>Sie k\u00f6nnen die Erfassung und Verarbeitung Ihrer Daten durch Google verhindern, indem Sie das unter dem folgenden Link verf\u00fcgbare Browser-Plugin herunterladen und installieren: <a href=\"https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/tools.google.com\/dlpage\/gaoptout?hl=de<\/a>.<\/p>\n<p>Mehr Informationen zum Umgang mit Nutzerdaten bei Google Analytics finden Sie in der Datenschutzerkl\u00e4rung von Google: <a href=\"https:\/\/support.google.com\/analytics\/answer\/6004245?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/support.google.com\/analytics\/answer\/6004245?hl=de<\/a>.<\/p>\n<h4>Google-Signale<\/h4>\n<p>Wir nutzen Google-Signale. Wenn Sie unsere Website besuchen, erfasst Google Analytics u.&nbsp;a. Ihren Standort, Suchverlauf und YouTube-Verlauf sowie demografische Daten (Besucherdaten). Diese Daten k\u00f6nnen mit Hilfe von Google-Signal f\u00fcr personalisierte Werbung verwendet werden. Wenn Sie \u00fcber ein Google-Konto verf\u00fcgen, werden die Besucherdaten von Google-Signal mit Ihrem Google-Konto verkn\u00fcpft und f\u00fcr personalisierte Werbebotschaften verwendet. Die Daten werden au\u00dferdem f\u00fcr die Erstellung anonymisierter Statistiken zum Nutzerverhalten unserer User verwendet.<\/p>\n<h4>Auftragsverarbeitung<\/h4>\n<p>Wir haben mit Google einen Vertrag zur Auftragsverarbeitung abgeschlossen und setzen die strengen Vorgaben der deutschen Datenschutzbeh\u00f6rden bei der Nutzung von Google Analytics vollst\u00e4ndig um.<\/p>\n<h4>Google Analytics E-Commerce-Messung<\/h4>\n<p>Diese Website nutzt die Funktion \u201eE-Commerce-Messung\u201c von Google Analytics. Mit Hilfe von E-Commerce-Messung kann der Websitebetreiber das Kaufverhalten der Websitebesucher zur Verbesserung seiner Online-Marketing-Kampagnen analysieren. Hierbei werden Informationen, wie zum Beispiel die get\u00e4tigten Bestellungen, durchschnittliche Bestellwerte, Versandkosten und die Zeit von der Ansicht bis zum Kauf eines Produktes erfasst. Diese Daten k\u00f6nnen von Google unter einer Transaktions-ID zusammengefasst werden, die dem jeweiligen Nutzer bzw. dessen Ger\u00e4t zugeordnet ist.<\/p>\n<h4>Speicherdauer<\/h4>\n<p>Bei Google gespeicherte Daten auf Nutzer- und Ereignisebene, die mit Cookies, Nutzerkennungen (z.&nbsp;B. User ID) oder Werbe-IDs (z.&nbsp;B. DoubleClick-Cookies, Android-Werbe-ID) verkn\u00fcpft sind, werden nach 2 Monaten anonymisiert bzw. gel\u00f6scht. Details hierzu ersehen Sie unter folgendem Link: <a href=\"https:\/\/support.google.com\/analytics\/answer\/7667196?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/support.google.com\/analytics\/answer\/7667196?hl=de<\/a><\/p>\n<h3>Google Ads<\/h3>\n<p>Der Websitebetreiber verwendet Google Ads. Google Ads ist ein Online-Werbeprogramm der Google Ireland Limited (\u201eGoogle\u201c), Gordon House, Barrow Street, Dublin 4, Irland.<\/p>\n<p>Google Ads erm\u00f6glicht es uns Werbeanzeigen in der Google-Suchmaschine oder auf Drittwebseiten auszuspielen, wenn der Nutzer bestimmte Suchbegriffe bei Google eingibt (Keyword-Targeting). Ferner k\u00f6nnen zielgerichtete Werbeanzeigen anhand der bei Google vorhandenen Nutzerdaten (z.&nbsp;B. Standortdaten und Interessen) ausgespielt werden (Zielgruppen-Targeting). Wir als Websitebetreiber k\u00f6nnen diese Daten quantitativ auswerten, indem wir beispielsweise analysieren, welche Suchbegriffe zur Ausspielung unserer Werbeanzeigen gef\u00fchrt haben und wie viele Anzeigen zu entsprechenden Klicks gef\u00fchrt haben.<\/p>\n<p>Die Nutzung von Google Ads erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Der Websitebetreiber hat ein berechtigtes Interesse an einer m\u00f6glichst effektiven Vermarktung seiner Dienstleistung Produkte.<\/p>\n<p>Die Daten\u00fcbertragung in die USA wird auf die Standardvertragsklauseln der EU-Kommission gest\u00fctzt. Details finden Sie hier: <a href=\"https:\/\/policies.google.com\/privacy\/frameworks\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/privacy\/frameworks<\/a> und <a href=\"https:\/\/privacy.google.com\/businesses\/controllerterms\/mccs\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/privacy.google.com\/businesses\/controllerterms\/mccs\/<\/a>.<\/p>\n<h3>Google Remarketing<\/h3>\n<p>Diese Website nutzt die Funktionen von Google Analytics Remarketing. Anbieter ist die Google Ireland Limited (\u201eGoogle\u201c), Gordon House, Barrow Street, Dublin 4, Irland.<\/p>\n<p>Google Remarketing analysiert Ihr Nutzerverhalten auf unserer Website (z.&nbsp;B. Klick auf bestimmte Produkte), um Sie in bestimmte Werbe-Zielgruppen einzuordnen und Ihnen anschlie\u00dfend beim Besuch von anderen Onlineangeboten passende Webebotschaften auszuspielen (Remarketing bzw. Retargeting).<\/p>\n<p>Des Weiteren k\u00f6nnen die mit Google Remarketing erstellten Werbe-Zielgruppen mit den ger\u00e4te\u00fcbergreifenden Funktionen von Google verkn\u00fcpft werden. Auf diese Weise k\u00f6nnen interessenbezogene, personalisierte Werbebotschaften, die in Abh\u00e4ngigkeit Ihres fr\u00fcheren Nutzungs- und Surfverhaltens auf einem Endger\u00e4t (z.&nbsp;B. Handy) an Sie angepasst wurden auch auf einem anderen Ihrer Endger\u00e4te (z.&nbsp;B. Tablet oder PC) angezeigt werden.<\/p>\n<p>Wenn Sie \u00fcber einen Google-Account verf\u00fcgen, k\u00f6nnen Sie der personalisierten Werbung unter folgendem Link widersprechen: <a href=\"https:\/\/www.google.com\/settings\/ads\/onweb\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.google.com\/settings\/ads\/onweb\/<\/a>.<\/p>\n<p>Die Nutzung von Google Remarketing erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Der Websitebetreiber hat ein berechtigtes Interesse an einer m\u00f6glichst effektiven Vermarktung seiner Produkte. Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO; die Einwilligung ist jederzeit widerrufbar.<\/p>\n<p>Weitergehende Informationen und die Datenschutzbestimmungen finden Sie in der Datenschutzerkl\u00e4rung von Google unter: <a href=\"https:\/\/policies.google.com\/technologies\/ads?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/technologies\/ads?hl=de<\/a>.<\/p>\n<h3>Google Conversion-Tracking<\/h3>\n<p>Diese Website nutzt Google Conversion Tracking. Anbieter ist die Google Ireland Limited (\u201eGoogle\u201c), Gordon House, Barrow Street, Dublin 4, Irland.<\/p>\n<p>Mit Hilfe von Google-Conversion-Tracking k\u00f6nnen Google und wir erkennen, ob der Nutzer bestimmte Aktionen durchgef\u00fchrt hat. So k\u00f6nnen wir beispielsweise auswerten, welche Buttons auf unserer Website wie h\u00e4ufig geklickt und welche Produkte besonders h\u00e4ufig angesehen oder gekauft wurden. Diese Informationen dienen dazu, Conversion-Statistiken zu erstellen. Wir erfahren die Gesamtanzahl der Nutzer, die auf unsere Anzeigen geklickt haben und welche Aktionen sie durchgef\u00fchrt haben. Wir erhalten keine Informationen, mit denen wir den Nutzer pers\u00f6nlich identifizieren k\u00f6nnen. Google selbst nutzt zur Identifikation Cookies oder vergleichbare Wiedererkennungstechnologien.<\/p>\n<p>Die Nutzung von Google Conversion-Tracking erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Der Websitebetreiber hat ein berechtigtes Interesse an der Analyse des Nutzerverhaltens, um sowohl sein Webangebot als auch seine Werbung zu optimieren. Sofern eine entsprechende Einwilligung abgefragt wurde (z.&nbsp;B. eine Einwilligung zur Speicherung von Cookies), erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO; die Einwilligung ist jederzeit widerrufbar.<\/p>\n<p>Mehr Informationen zu Google Conversion-Tracking finden Sie in den Datenschutzbestimmungen von Google: <a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/privacy?hl=de<\/a>.<\/p>\n<h3>Facebook Pixel<\/h3>\n<p>Diese Website nutzt zur Konversionsmessung der Besucheraktions-Pixel von Facebook. Anbieter dieses Dienstes ist die Meta Platforms Ireland Limited, 4 Grand Canal Square, Dublin 2, Irland. Die erfassten Daten werden nach Aussage von Facebook jedoch auch in die USA und in andere Drittl\u00e4nder \u00fcbertragen.<\/p>\n<p>So kann das Verhalten der Seitenbesucher nachverfolgt werden, nachdem diese durch Klick auf eine Facebook-Werbeanzeige auf die Website des Anbieters weitergeleitet wurden. Dadurch k\u00f6nnen die Wirksamkeit der Facebook-Werbeanzeigen f\u00fcr statistische und Marktforschungszwecke ausgewertet werden und zuk\u00fcnftige Werbema\u00dfnahmen optimiert werden.<\/p>\n<p>Die erhobenen Daten sind f\u00fcr uns als Betreiber dieser Website anonym, wir k\u00f6nnen keine R\u00fcckschl\u00fcsse auf die Identit\u00e4t der Nutzer ziehen. Die Daten werden aber von Facebook gespeichert und verarbeitet, sodass eine Verbindung zum jeweiligen Nutzerprofil m\u00f6glich ist und Facebook die Daten f\u00fcr eigene Werbezwecke, entsprechend der <a href=\"https:\/\/de-de.facebook.com\/about\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">Facebook-Datenverwendungsrichtlinie<\/a> verwenden kann. Dadurch kann Facebook das Schalten von Werbeanzeigen auf Seiten von Facebook sowie au\u00dferhalb von Facebook erm\u00f6glichen. Diese Verwendung der Daten kann von uns als Seitenbetreiber nicht beeinflusst werden.<\/p>\n<p>Die Nutzung von Facebook-Pixel erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Der Websitebetreiber hat ein berechtigtes Interesse an effektiven Werbema\u00dfnahmen unter Einschluss der sozialen Medien. Sofern eine entsprechende Einwilligung abgefragt wurde (z.&nbsp;B. eine Einwilligung zur Speicherung von Cookies), erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO; die Einwilligung ist jederzeit widerrufbar.<\/p>\n<p>Die Daten\u00fcbertragung in die USA wird auf die Standardvertragsklauseln der EU-Kommission gest\u00fctzt. Details finden Sie hier: <a href=\"https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum<\/a> und <a href=\"https:\/\/de-de.facebook.com\/help\/566994660333381\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/de-de.facebook.com\/help\/566994660333381<\/a>.<\/p>\n<p>Soweit mit Hilfe des hier beschriebenen Tools personenbezogene Daten auf unserer Website erfasst und an Facebook weitergeleitet werden, sind wir und die Meta Platforms Ireland Limited, 4 Grand Canal Square, Grand Canal Harbour, Dublin 2, Irland gemeinsam f\u00fcr diese Datenverarbeitung verantwortlich (Art. 26 DSGVO). Die gemeinsame Verantwortlichkeit beschr\u00e4nkt sich dabei ausschlie\u00dflich auf die Erfassung der Daten und deren Weitergabe an Facebook. Die nach der Weiterleitung erfolgende Verarbeitung durch Facebook ist nicht Teil der gemeinsamen Verantwortung. Die uns gemeinsam obliegenden Verpflichtungen wurden in einer Vereinbarung \u00fcber gemeinsame Verarbeitung festgehalten. Den Wortlaut der Vereinbarung finden Sie unter: <a href=\"https:\/\/www.facebook.com\/legal\/controller_addendum\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/legal\/controller_addendum<\/a>. Laut dieser Vereinbarung sind wir f\u00fcr die Erteilung der Datenschutzinformationen beim Einsatz des Facebook-Tools und f\u00fcr die datenschutzrechtlich sichere Implementierung des Tools auf unserer Website verantwortlich. F\u00fcr die Datensicherheit der Facebook-Produkte ist Facebook verantwortlich. Betroffenenrechte (z.&nbsp;B. Auskunftsersuchen) hinsichtlich der bei Facebook verarbeiteten Daten k\u00f6nnen Sie direkt bei Facebook geltend machen. Wenn Sie die Betroffenenrechte bei uns geltend machen, sind wir verpflichtet, diese an Facebook weiterzuleiten.<\/p>\n<p>In den Datenschutzhinweisen von Facebook finden Sie weitere Hinweise zum Schutz Ihrer Privatsph\u00e4re: <a href=\"https:\/\/de-de.facebook.com\/about\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/de-de.facebook.com\/about\/privacy\/<\/a>.<\/p>\n<p>Sie k\u00f6nnen au\u00dferdem die Remarketing-Funktion \u201eCustom Audiences\u201c im Bereich Einstellungen f\u00fcr Werbeanzeigen unter <a href=\"https:\/\/www.facebook.com\/ads\/preferences\/?entry_product=ad_settings_screen\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/ads\/preferences\/?entry_product=ad_settings_screen<\/a> deaktivieren. Dazu m\u00fcssen Sie bei Facebook angemeldet sein.<\/p>\n<p>Wenn Sie kein Facebook Konto besitzen, k\u00f6nnen Sie nutzungsbasierte Werbung von Facebook auf der Website der European Interactive Digital Advertising Alliance deaktivieren: <a href=\"http:\/\/www.youronlinechoices.com\/de\/praferenzmanagement\/\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/www.youronlinechoices.com\/de\/praferenzmanagement\/<\/a>.<\/p>\n<h2>7. Plugins und Tools<\/h2>\n<h3>YouTube mit erweitertem Datenschutz<\/h3>\n<p>Diese Website bindet Videos der YouTube ein. Betreiber der Seiten ist die Google Ireland Limited (\u201eGoogle\u201c), Gordon House, Barrow Street, Dublin 4, Irland.<\/p>\n<p>Wir nutzen YouTube im erweiterten Datenschutzmodus. Dieser Modus bewirkt laut YouTube, dass YouTube keine Informationen \u00fcber die Besucher auf dieser Website speichert, bevor diese sich das Video ansehen. Die Weitergabe von Daten an YouTube-Partner wird durch den erweiterten Datenschutzmodus hingegen nicht zwingend ausgeschlossen. So stellt YouTube \u2013 unabh\u00e4ngig davon, ob Sie sich ein Video ansehen \u2013 eine Verbindung zum Google DoubleClick-Netzwerk her.<\/p>\n<p>Sobald Sie ein YouTube-Video auf dieser Website starten, wird eine Verbindung zu den Servern von YouTube hergestellt. Dabei wird dem YouTube-Server mitgeteilt, welche unserer Seiten Sie besucht haben. Wenn Sie in Ihrem YouTube-Account eingeloggt sind, erm\u00f6glichen Sie YouTube, Ihr Surfverhalten direkt Ihrem pers\u00f6nlichen Profil zuzuordnen. Dies k\u00f6nnen Sie verhindern, indem Sie sich aus Ihrem YouTube-Account ausloggen.<\/p>\n<p>Des Weiteren kann YouTube nach Starten eines Videos verschiedene Cookies auf Ihrem Endger\u00e4t speichern oder vergleichbare Wiedererkennungstechnologien (z. B. Device-Fingerprinting) einsetzen. Auf diese Weise kann YouTube Informationen \u00fcber Besucher dieser Website erhalten. Diese Informationen werden u. a. verwendet, um Videostatistiken zu erfassen, die Anwenderfreundlichkeit zu verbessern und Betrugsversuchen vorzubeugen.<\/p>\n<p>Gegebenenfalls k\u00f6nnen nach dem Start eines YouTube-Videos weitere Datenverarbeitungsvorg\u00e4nge ausgel\u00f6st werden, auf die wir keinen Einfluss haben.<\/p>\n<p>Die Nutzung von YouTube erfolgt im Interesse einer ansprechenden Darstellung unserer Online-Angebote. Dies stellt ein berechtigtes Interesse im Sinne von Art. 6 Abs. 1 lit. f DSGVO dar. Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO; die Einwilligung ist jederzeit widerrufbar.<\/p>\n<p>Weitere Informationen \u00fcber Datenschutz bei YouTube finden Sie in deren Datenschutzerkl\u00e4rung unter: <a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/privacy?hl=de<\/a>.<\/p>\n<h3>Google Fonts (lokales Hosting)<\/h3>\n<p>Diese Seite nutzt zur einheitlichen Darstellung von Schriftarten so genannte Google Fonts, die von Google bereitgestellt werden. Die Google Fonts sind lokal installiert. Eine Verbindung zu Servern von Google findet dabei nicht statt.<\/p>\n<p>Weitere Informationen zu Google Fonts finden Sie unter <a href=\"https:\/\/developers.google.com\/fonts\/faq\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/developers.google.com\/fonts\/faq<\/a> und in der Datenschutzerkl\u00e4rung von Google: <a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/privacy?hl=de<\/a>.<\/p>\n<h3>Font Awesome<\/h3>\n<p>Diese Seite nutzt zur einheitlichen Darstellung von Schriftarten und Symbolen Font Awesome. Anbieter ist die Fonticons, Inc., 6 Porter Road Apartment 3R, Cambridge, Massachusetts, USA.<\/p>\n<p>Beim Aufruf einer Seite l\u00e4dt Ihr Browser die ben\u00f6tigten Fonts in ihren Browsercache, um Texte, Schriftarten und Symbole korrekt anzuzeigen. Zu diesem Zweck muss der von Ihnen verwendete Browser Verbindung zu den Servern von Font Awesome aufnehmen. Hierdurch erlangt Font Awesome Kenntnis dar\u00fcber, dass \u00fcber Ihre IP-Adresse diese Website aufgerufen wurde. Die Nutzung von Font Awesome erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Wir haben ein berechtigtes Interesse an der einheitlichen Darstellung des Schriftbildes auf unserer Website. Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TTDSG, soweit die Einwilligung die Speicherung von Cookies oder den Zugriff auf Informationen im Endger\u00e4t des Nutzers (z.&nbsp;B. Device-Fingerprinting) im Sinne des TTDSG umfasst. Die Einwilligung ist jederzeit widerrufbar.<\/p>\n<p>Wenn Ihr Browser Font Awesome nicht unterst\u00fctzt, wird eine Standardschrift von Ihrem Computer genutzt.<\/p>\n<p>Weitere Informationen zu Font Awesome finden Sie&nbsp;und in der Datenschutzerkl\u00e4rung von Font Awesome unter: <a href=\"https:\/\/fontawesome.com\/privacy\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/fontawesome.com\/privacy<\/a>.<\/p>\n<h3>Google Maps<\/h3>\n<p>Diese Seite nutzt den Kartendienst Google Maps. Anbieter ist die Google Ireland Limited (\u201eGoogle\u201c), Gordon House, Barrow Street, Dublin 4, Irland.<\/p>\n<p>Zur Nutzung der Funktionen von Google Maps ist es notwendig, Ihre IP-Adresse zu speichern. Diese Informationen werden in der Regel an einen Server von Google in den USA \u00fcbertragen und dort gespeichert. Der Anbieter dieser Seite hat keinen Einfluss auf diese Daten\u00fcbertragung. Wenn Google Maps aktiviert ist, kann Google zum Zwecke der einheitlichen Darstellung der Schriftarten Google Fonts verwenden. Beim Aufruf von Google Maps l\u00e4dt Ihr Browser die ben\u00f6tigten Web Fonts in ihren Browsercache, um Texte und Schriftarten korrekt anzuzeigen.<\/p>\n<p>Die Nutzung von Google Maps erfolgt im Interesse einer ansprechenden Darstellung unserer Online-Angebote und an einer leichten Auffindbarkeit der von uns auf der Website angegebenen Orte. Dies stellt ein berechtigtes Interesse im Sinne von Art. 6 Abs. 1 lit. f DSGVO dar. Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TTDSG, soweit die Einwilligung die Speicherung von Cookies oder den Zugriff auf Informationen im Endger\u00e4t des Nutzers (z.&nbsp;B. Device-Fingerprinting) im Sinne des TTDSG umfasst. Die Einwilligung ist jederzeit widerrufbar.<\/p>\n<p>Die Daten\u00fcbertragung in die USA wird auf die Standardvertragsklauseln der EU-Kommission gest\u00fctzt. Details finden Sie hier: <a href=\"https:\/\/privacy.google.com\/businesses\/gdprcontrollerterms\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/privacy.google.com\/businesses\/gdprcontrollerterms\/<\/a> und <a href=\"https:\/\/privacy.google.com\/businesses\/gdprcontrollerterms\/sccs\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/privacy.google.com\/businesses\/gdprcontrollerterms\/sccs\/<\/a>.<\/p>\n<p>Mehr Informationen zum Umgang mit Nutzerdaten finden Sie in der Datenschutzerkl\u00e4rung von Google: <a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/privacy?hl=de<\/a>.<\/p>\n<h3>Google reCAPTCHA<\/h3>\n<p>Wir nutzen \u201eGoogle reCAPTCHA\u201c (im Folgenden \u201ereCAPTCHA\u201c) auf dieser Website. Anbieter ist die Google Ireland Limited (\u201eGoogle\u201c), Gordon House, Barrow Street, Dublin 4, Irland.<\/p>\n<p>Mit reCAPTCHA soll \u00fcberpr\u00fcft werden, ob die Dateneingabe auf dieser Website (z.&nbsp;B. in einem Kontaktformular) durch einen Menschen oder durch ein automatisiertes Programm erfolgt. Hierzu analysiert reCAPTCHA das Verhalten des Websitebesuchers anhand verschiedener Merkmale. Diese Analyse beginnt automatisch, sobald der Websitebesucher die Website betritt. Zur Analyse wertet reCAPTCHA verschiedene Informationen aus (z.&nbsp;B. IP-Adresse, Verweildauer des Websitebesuchers auf der Website oder vom Nutzer get\u00e4tigte Mausbewegungen). Die bei der Analyse erfassten Daten werden an Google weitergeleitet.<\/p>\n<p>Die reCAPTCHA-Analysen laufen vollst\u00e4ndig im Hintergrund. Websitebesucher werden nicht darauf hingewiesen, dass eine Analyse stattfindet.<\/p>\n<p>Die Speicherung und Analyse der Daten erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Der Websitebetreiber hat ein berechtigtes Interesse daran, seine Webangebote vor missbr\u00e4uchlicher automatisierter Aussp\u00e4hung und vor SPAM zu sch\u00fctzen. Sofern eine entsprechende Einwilligung abgefragt wurde, erfolgt die Verarbeitung ausschlie\u00dflich auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO und \u00a7 25 Abs. 1 TTDSG, soweit die Einwilligung die Speicherung von Cookies oder den Zugriff auf Informationen im Endger\u00e4t des Nutzers (z.&nbsp;B. Device-Fingerprinting) im Sinne des TTDSG umfasst. Die Einwilligung ist jederzeit widerrufbar.<\/p>\n<p>Weitere Informationen zu Google reCAPTCHA entnehmen Sie den Google-Datenschutzbestimmungen und den Google Nutzungsbedingungen unter folgenden Links: <a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/privacy?hl=de<\/a> und <a href=\"https:\/\/policies.google.com\/terms?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/terms?hl=de<\/a>.<\/p>\n<h2>8. Unsere Social-Media-Auftritte<\/h2>\n<h4>Datenverarbeitung durch soziale Netzwerke<\/h4>\n<p>Wir unterhalten \u00f6ffentlich zug\u00e4ngliche Profile in sozialen Netzwerken. Die im Einzelnen von uns genutzten sozialen Netzwerke finden<br>Sie weiter unten.<\/p>\n<p>Soziale Netzwerke wie Facebook, Twitter etc. k\u00f6nnen Ihr Nutzerverhalten in der Regel umfassend analysieren, wenn Sie deren Website oder eine Website mit integrierten Social-Media-Inhalten (z.&nbsp;B. Like-Buttons oder Werbebannern) besuchen. Durch den Besuch<br>unserer Social-Media-Pr\u00e4senzen werden zahlreiche datenschutzrelevante Verarbeitungsvorg\u00e4nge ausgel\u00f6st. Im Einzelnen:<\/p>\n<p>Wenn Sie in Ihrem Social-Media-Account eingeloggt sind und unsere Social-Media-Pr\u00e4senz besuchen, kann der Betreiber des Social-Media-Portals diesen Besuch Ihrem Benutzerkonto zuordnen. Ihre personenbezogenen Daten k\u00f6nnen unter Umst\u00e4nden aber auch dann erfasst werden, wenn Sie nicht eingeloggt sind oder keinen Account beim jeweiligen Social-Media-Portal besitzen. Diese Datenerfassung erfolgt in diesem Fall beispielsweise \u00fcber Cookies, die auf Ihrem Endger\u00e4t gespeichert werden oder durch Erfassung Ihrer IP-Adresse.<\/p>\n<p>Mit Hilfe der so erfassten Daten k\u00f6nnen die Betreiber der Social-Media-Portale Nutzerprofile erstellen, in denen Ihre Pr\u00e4ferenzen und Interessen hinterlegt sind. Auf diese Weise kann Ihnen interessenbezogene Werbung in- und au\u00dferhalb der jeweiligen Social-Media-Pr\u00e4senz angezeigt werden. Sofern Sie \u00fcber einen Account beim jeweiligen sozialen Netzwerk verf\u00fcgen, kann die interessenbezogene Werbung auf allen Ger\u00e4ten angezeigt werden, auf denen Sie eingeloggt sind oder eingeloggt waren.<\/p>\n<p>Bitte beachten Sie au\u00dferdem, dass wir nicht alle Verarbeitungsprozesse auf den Social-Media-Portalen nachvollziehen k\u00f6nnen. Je nach Anbieter k\u00f6nnen daher ggf. weitere Verarbeitungsvorg\u00e4nge von den Betreibern der Social-Media-Portale durchgef\u00fchrt werden. Details hierzu entnehmen Sie den Nutzungsbedingungen und Datenschutzbestimmungen der jeweiligen Social-Media-Portale.<\/p>\n<h4>Rechtsgrundlage<\/h4>\n<div>Unsere Social-Media-Auftritte sollen eine m\u00f6glichst umfassende Pr\u00e4senz im Internet gew\u00e4hrleisten. Hierbei handelt es sich um ein berechtigtes Interesse im Sinne von Art. 6 Abs. 1 lit. f DSGVO. Die von den sozialen Netzwerken initiierten Analyseprozesse beruhen ggf. auf abweichenden Rechtsgrundlagen, die von den Betreibern der sozialen Netzwerke anzugeben sind (z.&nbsp;B. Einwilligung im Sinne des Art. 6 Abs. 1 lit. a DSGVO).<\/div>\n<div>\n<h4>Verantwortlicher und Geltendmachung von Rechten<\/h4>\n<div>\n<p>Wenn Sie einen unserer Social-Media-Auftritte (z.&nbsp;B. Facebook) besuchen, sind wir gemeinsam mit dem Betreiber der Social-Media-Plattform f\u00fcr die bei diesem Besuch ausgel\u00f6sten Datenverarbeitungsvorg\u00e4nge verantwortlich. Sie k\u00f6nnen Ihre Rechte (Auskunft, Berichtigung, L\u00f6schung, Einschr\u00e4nkung der Verarbeitung, Daten\u00fcbertragbarkeit und Beschwerde) grunds\u00e4tzlich sowohl gg\u00fc. uns als<br>auch gg\u00fc. dem Betreiber des jeweiligen Social-Media-Portals (z.&nbsp;B. gg\u00fc. Facebook) geltend machen.<\/p>\n<p>Bitte beachten Sie, dass wir trotz der gemeinsamen Verantwortlichkeit mit den Social-Media-Portal-Betreibern nicht vollumf\u00e4nglich Einfluss auf die Datenverarbeitungsvorg\u00e4nge der Social-Media-Portale haben. Unsere M\u00f6glichkeiten richten sich ma\u00dfgeblich nach der Unternehmenspolitik des jeweiligen Anbieters.<\/p>\n<h4>Speicherdauer<\/h4>\n<div>\n<p>Die unmittelbar von uns \u00fcber die Social-Media-Pr\u00e4senz erfassten Daten werden von unseren Systemen gel\u00f6scht, sobald Sie uns zur L\u00f6schung auffordern, Ihre Einwilligung zur Speicherung widerrufen oder der Zweck f\u00fcr die Datenspeicherung entf\u00e4llt. Gespeicherte Cookies verbleiben auf Ihrem Endger\u00e4t, bis Sie sie l\u00f6schen. Zwingende gesetzliche Bestimmungen \u2013 insb. Aufbewahrungsfristen \u2013 bleiben unber\u00fchrt.<\/p>\n<p>Auf die Speicherdauer Ihrer Daten, die von den Betreibern der sozialen Netzwerke zu eigenen Zwecken gespeichert werden, haben wir keinen Einfluss. F\u00fcr Einzelheiten dazu informieren Sie sich bitte direkt bei den Betreibern der sozialen Netzwerke (z.&nbsp;B. in deren Datenschutzerkl\u00e4rung, siehe unten).<\/p>\n<h4>Soziale Netzwerke im Einzelnen<\/h4>\n<div>\n<h5>Facebook<\/h5>\n<div>\n<p>Wir verf\u00fcgen \u00fcber ein Profil bei Facebook. Anbieter dieses Dienstes ist die Meta Platforms Ireland Limited, 4 Grand Canal Square, Grand<br>Canal Harbour, Dublin 2, Irland. Die erfassten Daten werden nach Aussage von Facebook auch in die USA und in andere Drittl\u00e4nder \u00fcbertragen.<\/p>\n<p>Wir haben mit Facebook eine Vereinbarung \u00fcber gemeinsame Verarbeitung (Controller Addendum) geschlossen. In dieser Vereinbarung wird festgelegt, f\u00fcr welche Datenverarbeitungsvorg\u00e4nge wir bzw. Facebook verantwortlich ist, wenn Sie unsere Facebook-Page besuchen. Diese Vereinbarung k\u00f6nnen Sie unter folgendem Link einsehen: <a href=\"https:\/\/www.facebook.com\/legal\/terms\/page_controller_addendum\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/legal\/terms\/page_controller_addendum<\/a>.<\/p>\n<p><strong>Sie k\u00f6nnen Ihre Werbeeinstellungen selbstst\u00e4ndig in Ihrem Nutzer-Account anpassen. Klicken Sie hierzu auf folgenden Link und<br>loggen Sie sich ein:<\/strong> <a href=\"https:\/\/www.facebook.com\/settings?tab=ads\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/settings?tab=ads<\/a>.<\/p>\n<p>Die Daten\u00fcbertragung in die USA wird auf die Standardvertragsklauseln der EU-Kommission gest\u00fctzt. Details finden Sie hier: <a href=\"https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum<\/a> und <a href=\"https:\/\/de-de.facebook.com\/help\/566994660333381\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/de-de.facebook.com\/help\/566994660333381<\/a>.<\/p>\n<p>Details entnehmen Sie der Datenschutzerkl\u00e4rung von Facebook: <a href=\"https:\/\/www.facebook.com\/about\/privacy\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/about\/privacy\/<\/a>.<\/p>\n<h5>Instagram<\/h5>\n<div>\n<p>Wir verf\u00fcgen \u00fcber ein Profil bei Instagram. Anbieter dieses Dienstes ist die Meta Platforms Ireland Limited, 4 Grand Canal Square, Grand<br>Canal Harbour, Dublin 2, Irland.<\/p>\n<p>Die Daten\u00fcbertragung in die USA wird auf die Standardvertragsklauseln der EU-Kommission gest\u00fctzt. Details finden Sie hier: <a href=\"https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum<\/a>, <a href=\"https:\/\/help.instagram.com\/519522125107875\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/help.instagram.com\/519522125107875<\/a> und <a href=\"https:\/\/de-de.facebook.com\/help\/566994660333381\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/de-de.facebook.com\/help\/566994660333381<\/a>.<\/p>\n<p>Details zu deren Umgang mit Ihren personenbezogenen Daten entnehmen Sie der Datenschutzerkl\u00e4rung von Instagram: <a href=\"https:\/\/help.instagram.com\/519522125107875\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/help.instagram.com\/519522125107875<\/a>.<\/p>\n<h5>YouTube<\/h5>\n<div>Wir verf\u00fcgen \u00fcber ein Profil bei YouTube. Anbieter ist die Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irland. Details<br>zu deren Umgang mit Ihren personenbezogenen Daten entnehmen Sie der Datenschutzerkl\u00e4rung von YouTube: <a href=\"https:\/\/policies.google.com\/privacy?hl=de\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/policies.google.com\/privacy?hl=de<\/a>.<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"featured_media":8231,"template":"","class_list":["post-7312","bhv","type-bhv","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Datenschutz - havenhostel Deutschland<\/title>\n<meta name=\"description\" content=\"Der Schutz Ihrer privaten Daten ist uns bei der Verarbeitung personenbezogener Daten ein wichtiges Anliegen, das wir bei s\u00e4mtlichen Gesch\u00e4ftsprozessen stets ber\u00fccksichtigen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.havenhostel.de\/de\/bhv\/datenschutz\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutz - havenhostel Deutschland\" \/>\n<meta property=\"og:description\" content=\"Der Schutz Ihrer privaten Daten ist uns bei der Verarbeitung personenbezogener Daten ein wichtiges Anliegen, das wir bei s\u00e4mtlichen Gesch\u00e4ftsprozessen stets ber\u00fccksichtigen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.havenhostel.de\/de\/bhv\/datenschutz\/\" \/>\n<meta property=\"og:site_name\" content=\"havenhostel Deutschland\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-26T14:30:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.havenhostel.de\/wp-content\/uploads\/2021\/05\/Parkplatz-Titelbild-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"53\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.havenhostel.de\\\/de\\\/bhv\\\/datenschutz\\\/\",\"url\":\"https:\\\/\\\/www.havenhostel.de\\\/de\\\/bhv\\\/datenschutz\\\/\",\"name\":\"Datenschutz - havenhostel Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.havenhostel.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.havenhostel.de\\\/de\\\/bhv\\\/datenschutz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.havenhostel.de\\\/de\\\/bhv\\\/datenschutz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.havenhostel.de\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Parkplatz-Titelbild-scaled-1.jpg\",\"datePublished\":\"2020-12-30T14:34:10+00:00\",\"dateModified\":\"2024-11-26T14:30:14+00:00\",\"description\":\"Der Schutz Ihrer privaten Daten ist uns bei der Verarbeitung personenbezogener Daten ein wichtiges Anliegen, das wir bei s\u00e4mtlichen Gesch\u00e4ftsprozessen stets ber\u00fccksichtigen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.havenhostel.de\\\/de\\\/bhv\\\/datenschutz\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.havenhostel.de\\\/de\\\/bhv\\\/datenschutz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.havenhostel.de\\\/de\\\/bhv\\\/datenschutz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.havenhostel.de\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Parkplatz-Titelbild-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.havenhostel.de\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Parkplatz-Titelbild-scaled-1.jpg\",\"width\":2560,\"height\":1250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.havenhostel.de\\\/de\\\/bhv\\\/datenschutz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.havenhostel.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BHV\",\"item\":\"https:\\\/\\\/www.havenhostel.de\\\/de\\\/bhv\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Datenschutz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.havenhostel.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.havenhostel.de\\\/de\\\/\",\"name\":\"havenhostel Deutschland\",\"description\":\"Ein Zuhause f\u00fcr Alle!\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.havenhostel.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.havenhostel.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.havenhostel.de\\\/de\\\/#organization\",\"name\":\"havenhostel Deutschland\",\"url\":\"https:\\\/\\\/www.havenhostel.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.havenhostel.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.havenhostel.de\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/havenhostel-deutschland_logo_mit-Kontur_RGB.png\",\"contentUrl\":\"https:\\\/\\\/www.havenhostel.de\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/havenhostel-deutschland_logo_mit-Kontur_RGB.png\",\"width\":900,\"height\":300,\"caption\":\"havenhostel Deutschland\"},\"image\":{\"@id\":\"https:\\\/\\\/www.havenhostel.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.youtube.com\\\/user\\\/havenhostel\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutz - havenhostel Deutschland","description":"Der Schutz Ihrer privaten Daten ist uns bei der Verarbeitung personenbezogener Daten ein wichtiges Anliegen, das wir bei s\u00e4mtlichen Gesch\u00e4ftsprozessen stets ber\u00fccksichtigen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.havenhostel.de\/de\/bhv\/datenschutz\/","og_locale":"de_DE","og_type":"article","og_title":"Datenschutz - havenhostel Deutschland","og_description":"Der Schutz Ihrer privaten Daten ist uns bei der Verarbeitung personenbezogener Daten ein wichtiges Anliegen, das wir bei s\u00e4mtlichen Gesch\u00e4ftsprozessen stets ber\u00fccksichtigen.","og_url":"https:\/\/www.havenhostel.de\/de\/bhv\/datenschutz\/","og_site_name":"havenhostel Deutschland","article_modified_time":"2024-11-26T14:30:14+00:00","og_image":[{"width":2560,"height":1250,"url":"https:\/\/www.havenhostel.de\/wp-content\/uploads\/2021\/05\/Parkplatz-Titelbild-scaled-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"53\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.havenhostel.de\/de\/bhv\/datenschutz\/","url":"https:\/\/www.havenhostel.de\/de\/bhv\/datenschutz\/","name":"Datenschutz - havenhostel Deutschland","isPartOf":{"@id":"https:\/\/www.havenhostel.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.havenhostel.de\/de\/bhv\/datenschutz\/#primaryimage"},"image":{"@id":"https:\/\/www.havenhostel.de\/de\/bhv\/datenschutz\/#primaryimage"},"thumbnailUrl":"https:\/\/www.havenhostel.de\/wp-content\/uploads\/2021\/05\/Parkplatz-Titelbild-scaled-1.jpg","datePublished":"2020-12-30T14:34:10+00:00","dateModified":"2024-11-26T14:30:14+00:00","description":"Der Schutz Ihrer privaten Daten ist uns bei der Verarbeitung personenbezogener Daten ein wichtiges Anliegen, das wir bei s\u00e4mtlichen Gesch\u00e4ftsprozessen stets ber\u00fccksichtigen.","breadcrumb":{"@id":"https:\/\/www.havenhostel.de\/de\/bhv\/datenschutz\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.havenhostel.de\/de\/bhv\/datenschutz\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.havenhostel.de\/de\/bhv\/datenschutz\/#primaryimage","url":"https:\/\/www.havenhostel.de\/wp-content\/uploads\/2021\/05\/Parkplatz-Titelbild-scaled-1.jpg","contentUrl":"https:\/\/www.havenhostel.de\/wp-content\/uploads\/2021\/05\/Parkplatz-Titelbild-scaled-1.jpg","width":2560,"height":1250},{"@type":"BreadcrumbList","@id":"https:\/\/www.havenhostel.de\/de\/bhv\/datenschutz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.havenhostel.de\/de\/"},{"@type":"ListItem","position":2,"name":"BHV","item":"https:\/\/www.havenhostel.de\/de\/bhv\/"},{"@type":"ListItem","position":3,"name":"Datenschutz"}]},{"@type":"WebSite","@id":"https:\/\/www.havenhostel.de\/de\/#website","url":"https:\/\/www.havenhostel.de\/de\/","name":"havenhostel Deutschland","description":"Ein Zuhause f\u00fcr Alle!","publisher":{"@id":"https:\/\/www.havenhostel.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.havenhostel.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.havenhostel.de\/de\/#organization","name":"havenhostel Deutschland","url":"https:\/\/www.havenhostel.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.havenhostel.de\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.havenhostel.de\/wp-content\/uploads\/2020\/12\/havenhostel-deutschland_logo_mit-Kontur_RGB.png","contentUrl":"https:\/\/www.havenhostel.de\/wp-content\/uploads\/2020\/12\/havenhostel-deutschland_logo_mit-Kontur_RGB.png","width":900,"height":300,"caption":"havenhostel Deutschland"},"image":{"@id":"https:\/\/www.havenhostel.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.youtube.com\/user\/havenhostel"]}]}},"_links":{"self":[{"href":"https:\/\/www.havenhostel.de\/de\/wp-json\/wp\/v2\/bhv\/7312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.havenhostel.de\/de\/wp-json\/wp\/v2\/bhv"}],"about":[{"href":"https:\/\/www.havenhostel.de\/de\/wp-json\/wp\/v2\/types\/bhv"}],"version-history":[{"count":3,"href":"https:\/\/www.havenhostel.de\/de\/wp-json\/wp\/v2\/bhv\/7312\/revisions"}],"predecessor-version":[{"id":15044,"href":"https:\/\/www.havenhostel.de\/de\/wp-json\/wp\/v2\/bhv\/7312\/revisions\/15044"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.havenhostel.de\/de\/wp-json\/wp\/v2\/media\/8231"}],"wp:attachment":[{"href":"https:\/\/www.havenhostel.de\/de\/wp-json\/wp\/v2\/media?parent=7312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}